{"id":14775,"date":"2018-03-24T02:12:14","date_gmt":"2018-03-24T02:12:14","guid":{"rendered":"https:\/\/espacodosol.com\/blog.br\/?p=14775"},"modified":"2018-03-24T02:12:14","modified_gmt":"2018-03-24T02:12:14","slug":"os-beneficios-da-taioba-para-a-saude","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2018\/03\/24\/os-beneficios-da-taioba-para-a-saude\/","title":{"rendered":"Os Benef\u00edcios da Taioba Para a Sa\u00fade"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14776\" src=\"https:\/\/espacodosol.com\/blog.br\/wp-content\/uploads\/2018\/03\/taioba-xantosoma.jpg\" alt=\"\" width=\"1600\" height=\"1200\" \/><\/p>\n<p>A\u00a0<strong>taioba<\/strong>\u00a0n\u00e3o \u00e9 das hortali\u00e7as mais conhecidas no Brasil, pois ela costuma ser plantada nos quintais das casas e a sua produ\u00e7\u00e3o \u00e9 maior nos estados de Minas Gerais e Goi\u00e1s. Por\u00e9m, \u00e9 uma planta que devia ser consumida por todos devido ao seu elevado valor nutritivo.<\/p>\n<div id=\"quads-ad2\" class=\"quads-location quads-ad2\"><\/div>\n<p>Ela consegue oferecer diversos\u00a0<strong>benef\u00edcios para a nossa sa\u00fade<\/strong>\u00a0e pode ser consumida das mais diversas formas: em sopas, bolinhos, pizzas, crepes e outras tantas del\u00edcias. Essa folha faz um grande sucesso por ter o gosto parecido com o espinafre, por\u00e9m um pouco mais suave.<\/p>\n<p>Quer saber quais s\u00e3o os incr\u00edveis benef\u00edcios de adicion\u00e1-la ao seu card\u00e1pio? Ent\u00e3o continue por aqui!<\/p>\n<h2>Por que comer taioba?<\/h2>\n<h3>1. Melhora a vis\u00e3o<\/h3>\n<p>Se voc\u00ea tem problemas de vis\u00e3o, est\u00e1 mais do que na hora de come\u00e7ar a\u00a0<strong>consumir taioba<\/strong>. Esse benef\u00edcio que a hortali\u00e7a oferece \u00e9 por conta da vitamina A presente nela.<\/p>\n<p>J\u00e1 ouviram falar sobre cegueira noturna? As baixas taxas de vitamina A no organismo \u00e9 a causa para essa condi\u00e7\u00e3o. Como o pr\u00f3prio nome j\u00e1 diz, \u00e9 uma dificuldade de enxergar \u00e0 noite ou em locais escuros. Isso pode ser um problema, por exemplo, para quem dirige \u00e0 noite, especialmente caminhoneiros.<\/p>\n<p>Essa vitamina \u00e9 um dos ingredientes fundamentais para a s\u00edntese da rodopsina, uma subst\u00e2ncia que nos ajuda a diferenciar o claro do escuro.<\/p>\n<h3>2. A planta taioba fortalece os ossos<\/h3>\n<p>N\u00e3o \u00e9 apenas o leite que \u00e9 rico em c\u00e1lcio, as folhas verdes tamb\u00e9m possuem altos n\u00edveis desse mineral e quanto mais verde \u00e9 a folha, mais c\u00e1lcio ela tem.<\/p>\n<p>Essa regra tamb\u00e9m vale para a taioba que, al\u00e9m desse\u00a0<a href=\"https:\/\/pt.wikipedia.org\/wiki\/Nutriente\" target=\"_blank\" rel=\"noopener noreferrer\">nutriente<\/a>, tamb\u00e9m possui f\u00f3sforo, muito importante para constitui\u00e7\u00e3o e reparo \u00f3sseo. Comer a folha fortalece o sistema esquel\u00e9tico e, consequentemente, ajuda na preven\u00e7\u00e3o de doen\u00e7as como a\u00a0<a href=\"https:\/\/www.dietaeboasaude.com.br\/osteoporose-acesse-a-cartilha\/\">osteoporose<\/a>.<\/p>\n<h3>3. Melhora as defesas do corpo<\/h3>\n<p>O nosso sistema imunol\u00f3gico deve estar sempre pronto para nos defender de agentes invasores como v\u00edrus, bact\u00e9rias, fungos e outros. Uma forma de fortalec\u00ea-lo \u00e9 adicionando a taioba \u00e0 dieta.<\/p>\n<p>Isso ocorre por conta da presen\u00e7a de vitamina C, que \u00e9 um agente antioxidante e tamb\u00e9m aumenta as defesas do corpo. \u00c9 por isso que \u00e9 muito comum que seja indicado frutas ricas em vitamina C quando estamos resfriados como a laranja e o lim\u00e3o.<\/p>\n<h3>4. Alivia a constipa\u00e7\u00e3o<\/h3>\n<p>Constipa\u00e7\u00e3o nada mais \u00e9 que a popular\u00a0<a href=\"https:\/\/www.dietaeboasaude.com.br\/prisao-de-ventre-o-que-comer\/\">pris\u00e3o de ventre<\/a>. A pessoa passa dias sem defecar e isso pode causar muita dor, al\u00e9m de ser um sinal de que algo n\u00e3o vai bem no organismo.<\/p>\n<div id=\"quads-ad9\" class=\"quads-location quads-ad9\"><\/div>\n<p><a href=\"https:\/\/www.dietaeboasaude.com.br\/alimentos-ricos-em-fibras-soluveis\/\">Alimentos ricos em fibras<\/a>\u00a0como a taioba pode ajudar e muito esse tipo de situa\u00e7\u00e3o. \u00c9 que, ao chegarem ao intestino, elas aumentam os movimentos perist\u00e1lticos \u2013 respons\u00e1veis pela passagem bolo fecal no intestino at\u00e9 o destino final.<\/p>\n<div id=\"quads-ad3\" class=\"quads-location quads-ad3\"><\/div>\n<h3>5. Auxilia na preven\u00e7\u00e3o e tratamento da anemia<\/h3>\n<p>A\u00a0<strong>taioba<\/strong>\u00a0\u00e9 rica em ferro, nutriente essencial para a preven\u00e7\u00e3o da anemia (situa\u00e7\u00e3o que ocorre quando h\u00e1 uma baixa na quantidade de ferro no sangue conhecida como\u00a0<a href=\"https:\/\/www.dietaeboasaude.com.br\/anemia-ferropriva-como-combater\/\">anemia ferropriva<\/a>).<\/p>\n<p>A hemoglobina \u2013 c\u00e9lula vermelha \u2013 \u00e9 a respons\u00e1vel por levar oxig\u00eanio para as mais diversas partes do corpo. Por\u00e9m, essa c\u00e9lula s\u00f3 consegue fazer isso se o\u00a0<a href=\"https:\/\/www.dietaeboasaude.com.br\/10-alimentos-ricos-em-ferro\/\">ferro<\/a>\u00a0estiver conectado a ela. Assim, se h\u00e1 pouco ferro, consequente, h\u00e1 pouco oxig\u00eanio circulando no corpo.<\/p>\n<h3>6. Controla a press\u00e3o arterial<\/h3>\n<p>Os quadros de hipertens\u00e3o arterial s\u00e3o cada vez mais comuns e uma forma de\u00a0<a href=\"https:\/\/www.dietaeboasaude.com.br\/dieta-dash-emagrece-qual-o-cardapio\/\">controlar a press\u00e3o<\/a>\u00a0e tamb\u00e9m prevenir essa doen\u00e7a \u00e9 ingerindo taioba.<\/p>\n<p>Ela \u00e9 rica em pot\u00e1ssio \u2013 nutriente respons\u00e1vel pelo controle de s\u00f3dio na corrente sangu\u00ednea \u2013 e, por conta disso, tamb\u00e9m consegue controlar o ac\u00famulo de l\u00edquidos dentro dos vasos. Al\u00e9m da hipertens\u00e3o, esse desequil\u00edbrio da press\u00e3o tamb\u00e9m pode provocar o AVC (acidente vascular encef\u00e1lico).<\/p>\n<h2>Benef\u00edcios, e Diferen\u00e7a Entre Taioba e Inhame<\/h2>\n<div class=\"video_embed clearfix\">\n<div class=\"video_embed clearfix\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/u1ftw424tG8?feature=oembed\" width=\"500\" height=\"281\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div class=\"video_embed clearfix\"><\/div>\n<div class=\"video_embed clearfix\">Fonte:\u00a0https:\/\/www.dietaeboasaude.com.br\/taioba-beneficios-receita\/<\/div>\n<div class=\"video_embed clearfix\"><\/div>\n<div class=\"video_embed clearfix\"><\/div>\n<\/div>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 562<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>A\u00a0taioba\u00a0n\u00e3o \u00e9 das hortali\u00e7as mais conhecidas no Brasil, pois ela costuma ser plantada nos quintais das casas e a sua produ\u00e7\u00e3o \u00e9 maior nos estados de Minas Gerais e Goi\u00e1s. Por\u00e9m, \u00e9 uma planta que devia ser consumida por todos devido ao seu elevado valor nutritivo. Ela consegue oferecer diversos\u00a0benef\u00edcios para a nossa sa\u00fade\u00a0e pode [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-14775","post","type-post","status-publish","format-standard","hentry","category-alimentacao-natural"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/14775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=14775"}],"version-history":[{"count":0,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/14775\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=14775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=14775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=14775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}