{"id":15544,"date":"2019-01-05T01:39:36","date_gmt":"2019-01-05T01:39:36","guid":{"rendered":"https:\/\/espacodosol.com\/blog.br\/?p=15544"},"modified":"2019-01-05T01:39:36","modified_gmt":"2019-01-05T01:39:36","slug":"maca-de-elefante-fruta-exotica-que-alimenta-e-com-propriedades-medicinais","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2019\/01\/05\/maca-de-elefante-fruta-exotica-que-alimenta-e-com-propriedades-medicinais\/","title":{"rendered":"Ma\u00e7\u00e3-de-elefante fruta ex\u00f3tica que alimenta e com propriedades medicinais"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15545\" src=\"https:\/\/espacodosol.com\/blog.br\/wp-content\/uploads\/2019\/01\/Maca-de-elefante.jpg\" alt=\"\" width=\"800\" height=\"450\" \/><\/p>\n<p style=\"text-align: justify;\">Ma\u00e7\u00e3-de-elefante (<em>Dillenia indica<\/em>) \u00e9 conhecida popularmente de Flor-de-abril, \u00c1rvore-do-dinheiro, Bolsa-de-pastor e Dil\u00eania; e pertence \u00e0 fam\u00edlia Dileniaceae.<\/p>\n<h2 style=\"text-align: justify;\">Conhe\u00e7a a Ma\u00e7\u00e3-de-elefante<\/h2>\n<p style=\"text-align: justify;\">A planta \u00e9 origin\u00e1ria da \u00c1sia, mais especificamente da \u00cdndia, veio para o Brasil; possivelmente, com a comitiva de D. Jo\u00e3o VI como planta ornamental, foi espalhada em v\u00e1rias regi\u00f5es, mas n\u00e3o \u00e9 uma planta muito conhecida e pouco usada na gastronomia.<\/p>\n<p style=\"text-align: justify;\">\u00c9 uma \u00e1rvore ornamental com folhas grandes, enrugadas e seus frutos s\u00e3o grandes de casca dura, que se organiza por sobreposi\u00e7\u00e3o como se fosse uma cabe\u00e7a de repolho; os frutos, depois de formados, se assemelham a um coco verde e possuem sementes pequenas.<\/p>\n<h2 style=\"text-align: justify;\">Utiliza\u00e7\u00e3o da Ma\u00e7\u00e3-de-Elefante<\/h2>\n<p style=\"text-align: justify;\">A madeira da \u00e1rvore Ma\u00e7\u00e3-de-elefante \u00e9 muito utilizada na constru\u00e7\u00e3o civil e naval; pois sua madeira \u00e9 de boa qualidade e bem resistente. Na ro\u00e7a era utilizada como lenha para o fog\u00e3o a lenha ou fornalha.<\/p>\n<p style=\"text-align: justify;\">Em algumas regi\u00f5es brasileiras o fruto, que possui um polpa pegajosa, \u00e9 usado em receitas tais como picles, doces, sorvetes, xaropes e geleias, mas n\u00e3o h\u00e1 o costume de ingeri-lo in natura, pois possui um cheiro bem forte.<\/p>\n<p style=\"text-align: justify;\">A polpa, a semente e a casca da fruta possuem excelentes fontes de prote\u00ednas, carboidratos e amino\u00e1cidos, respectivamente, que s\u00e3o elementos muito ben\u00e9ficos \u00e0 sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">Em alguns pa\u00edses, como por exemplo, o Panam\u00e1 o fruto \u00e9 cozido, ingerido para aliviar problemas de reumatismo; na Indon\u00e9sia, a fruta \u00e9 misturada ao mel e ingerida no caf\u00e9 da manh\u00e3; na Tail\u00e2ndia, o costume \u00e9 se alimentar das folhas em saladas e na \u00cdndia a polpa \u00e9 usada em chutneys salgados, muito apreciados pelos indianos.<\/p>\n<h2 style=\"text-align: justify;\">Utiliza\u00e7\u00e3o da Ma\u00e7\u00e3-de-elefante na medicina popular<\/h2>\n<p style=\"text-align: justify;\">H\u00e1 estudos e pesquisas com a ma\u00e7\u00e3-de-elefante que comprovam a\u00e7\u00e3o terap\u00eautica em tratamento de dores musculares , em caso de inflama\u00e7\u00f5es e ainda como analg\u00e9sico no tratamento do reumatismo e da artrose.<\/p>\n<p style=\"text-align: justify;\">A fruta tem propriedades ben\u00e9ficas para a digest\u00e3o, para acabar com vermes intestinais e melhora da disenteria. Misturadas ao mel e cominho ajudam no tratamento da diarreia e m\u00e1 digest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Possui propriedades laxativas; o suco misturado com a\u00e7\u00facar e \u00e1gua morna purificam o sangue e o aparelho intestinal. O uso das folhas melhora dor de garganta, doen\u00e7as respirat\u00f3rias e tosse.<\/p>\n<p style=\"text-align: justify;\">Segundo cren\u00e7a popular, o fruto maduro deve ser batido em liquidificador com um pouco de \u00e1gua, o suficiente para que o aparelho consiga funcionar, transfira para um recipiente de vidro, sem incid\u00eancia de luz, deixe curtir por mais ou menos uma hora. Para usar, basta passar o preparo no local dolorido.<\/p>\n<p style=\"text-align: justify;\">As plantas medicinais n\u00e3o substituem o acompanhamento m\u00e9dico e em altas doses podem ser prejudiciais \u00e0 sa\u00fade.<\/p>\n<p>Fonte:\u00a0https:\/\/www.coisasdaroca.com\/plantas-medicinais\/maca-de-elefante.html<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 671<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>Ma\u00e7\u00e3-de-elefante (Dillenia indica) \u00e9 conhecida popularmente de Flor-de-abril, \u00c1rvore-do-dinheiro, Bolsa-de-pastor e Dil\u00eania; e pertence \u00e0 fam\u00edlia Dileniaceae. Conhe\u00e7a a Ma\u00e7\u00e3-de-elefante A planta \u00e9 origin\u00e1ria da \u00c1sia, mais especificamente da \u00cdndia, veio para o Brasil; possivelmente, com a comitiva de D. Jo\u00e3o VI como planta ornamental, foi espalhada em v\u00e1rias regi\u00f5es, mas n\u00e3o \u00e9 uma planta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-15544","post","type-post","status-publish","format-standard","hentry","category-alimentacao-natural"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/15544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=15544"}],"version-history":[{"count":0,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/15544\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=15544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=15544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=15544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}