{"id":15642,"date":"2019-02-20T02:06:00","date_gmt":"2019-02-20T02:06:00","guid":{"rendered":"https:\/\/espacodosol.com\/blog.br\/?p=15642"},"modified":"2019-02-20T02:06:00","modified_gmt":"2019-02-20T02:06:00","slug":"sintomas-provocados-pelas-energias-do-momento","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2019\/02\/20\/sintomas-provocados-pelas-energias-do-momento\/","title":{"rendered":"Sintomas provocados pelas energias do momento"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15532\" src=\"https:\/\/espacodosol.com\/blog.br\/wp-content\/uploads\/2018\/12\/frequencia1.jpg\" alt=\"\" width=\"564\" height=\"734\" \/><\/p>\n<p>Amados!<\/p>\n<p>Estamos entrando cada vez mais na profundidade da Luz plena. \u00c9 tanta energia fot\u00f4nica enviada em dire\u00e7\u00e3o \u00e0 Terra, desde 2012, que est\u00e3o vindo em forma de ondas intermitentes.<\/p>\n<p>Caso essa energia viesse toda de uma vez vez s\u00f3, ser\u00edamos pulverizados instantaneamente.<\/p>\n<p>Mas o Universo \u00e9 s\u00e1bio e tem suas Leis pr\u00f3prias que rege os mundos e a vida.<\/p>\n<p>Essas ondas v\u00eam em sequ\u00eancias e num crescente, para que o nosso corpo possa suportar.<\/p>\n<p>\u00c9 como uma plantinha que est\u00e1 torta, se queremos endireit\u00e1-la, precisamos fazer aos poucos e com cuidado para n\u00e3o quebr\u00e1-la.<\/p>\n<p>Assim o nosso Planeta est\u00e1 sendo \u201cendireitado\u201d de suas anomalias energ\u00e9ticas em que estava submetido.<\/p>\n<p>Essas ondas est\u00e3o sendo cont\u00ednuas. Intercaladas eventualmente com ondas maiores, elas exigem o m\u00e1ximo de nossa resist\u00eancia. Tivemos em 21-01-19 uma grande onda vinda do Sol Central Gal\u00e1ctico.<\/p>\n<p>Ela serviu para o ancoramento definitivo da Luz na Terra. A medita\u00e7\u00e3o em massa durante o eclipse lunar daquele dia, atingiu e superou em 3 vezes a massa cr\u00edtica necess\u00e1ria de consci\u00eancias conectadas com essa inten\u00e7\u00e3o.<\/p>\n<p>De l\u00e1 at\u00e9 21 de mar\u00e7o, ou seja, no Equin\u00f3cio do outono para o Hemisf\u00e9rio Sul, essa energia est\u00e1 formando ilhas de luz inacess\u00edveis \u00e0 qualquer for\u00e7a das Trevas.<\/p>\n<p>Aos poucos, elas v\u00e3o crescendo, na medida que mais pessoas despertas v\u00e3o se agrupando nelas.<\/p>\n<p>E na medida que crescem, juntam-se umas \u00e0s outras, ocupando os espa\u00e7os que antes era das Sombras.<\/p>\n<p>Essa for\u00e7a magn\u00e9tica da Luz que vem de cima para baixo, est\u00e1 se encontrando com a for\u00e7a magn\u00e9tica de alta vibra\u00e7\u00e3o que vem do interior da Terra (Agharta).<\/p>\n<p>Isso chama-se COMPRESS\u00c3O. Essa compress\u00e3o vai aumentando a cada dia, e quando essas duas for\u00e7as se encontrarem, ocorrer\u00e1 o EVENTO.<\/p>\n<p>Quanto mais Luz chega \u00e0 Terra, maior \u00e9 a press\u00e3o. E quanto maior a press\u00e3o, menos espa\u00e7o as Sombras ter\u00e3o. Isso tamb\u00e9m est\u00e1 provocando uma correria desenfreada dos Esp\u00edritos desencarnados e, principalmente um desespero sem tamanho dos encarnados que se comprazem com elas. N\u00e3o h\u00e1 mais onde se esconder e nem para onde correr.<\/p>\n<p>Observem os acontecimentos, principalmente aos relacionados ao Velho Poder. Toda a Cabala Escura est\u00e1 sendo desmantelada.<\/p>\n<p>As surpresas ser\u00e3o a cada dia maiores.<\/p>\n<p>Mas o que me leva a escrever o texto de hoje, \u00e9 a necessidade de esclarecer alguma coisa em rela\u00e7\u00e3o aos sintomas estranhos que muitos est\u00e3o sentindo.<\/p>\n<p>Obviamente, a entrada deste fluxo energ\u00e9tico intenso, est\u00e1 limpando as velhas energias que ainda t\u00eam algum registro em nossas mem\u00f3rias celulares.<\/p>\n<p>Neste sentido, cada um tem a sua \u201cv\u00e1lvula de escape\u201d. \u00c9 a parte do corpo que sente exatamente onde est\u00e1 sendo liberada.<\/p>\n<p>Pode ser f\u00edsico, emocional, mental ou espiritual. Dores em qualquer parte do corpo, desajustes emocionais, sensa\u00e7\u00f5es de dist\u00farbios mentais ou des\u00e2nimo e d\u00favidas com as suas cren\u00e7as atuais.<\/p>\n<p>Esses sintomas s\u00e3o in\u00fameros, por\u00e9m, voc\u00ea deve estar sentindo apenas um ou alguns deles.<br \/>\nOs sintomas f\u00edsicos j\u00e1 v\u00eam acontecendo a mais tempo.<\/p>\n<p>J\u00e1 n\u00e3o preocupam mais a maioria de voc\u00eas. Outros s\u00e3o mais recentes, e por isso, geram uma certa preocupa\u00e7\u00e3o.<\/p>\n<p>Neste final de semana, por exemplo, tivemos um pico de Luz t\u00e3o forte que fez a Escala Schumann atingir a maior vibra\u00e7\u00e3o desde que ela foi criada h\u00e1 mais de 70 anos.<\/p>\n<p>Essa eleva\u00e7\u00e3o das vibra\u00e7\u00f5es provocou um sintoma novo. Muitas pessoas tiveram a impress\u00e3o de perder a consci\u00eancia por curtos per\u00edodos. Mas nada a preocupar, pois a partir de hoje, vai estabilizar novamente.<\/p>\n<p>Outro sintoma bastante interessante \u00e9 uma sensa\u00e7\u00e3o de ang\u00fastia. Provoca um certo des\u00e2nimo e uma sensa\u00e7\u00e3o de impot\u00eancia. Em certos momentos, podemos sentir vontade de desistir de tudo o que estamos fazendo. Isso est\u00e1 relacionado ao nosso subconsciente.<\/p>\n<p>O nosso EU SUPERIOR sabe que estamos a cada dia mais pr\u00f3ximos do Final do Ciclo de Terceira Dimens\u00e3o. Essa ang\u00fastia nada mais \u00e9 que a ansiedade que o nosso Esp\u00edrito sente. Ele tem pressa pois percorreu tantos mil\u00eanios para, finalmente agora chegar ao final desta grande maratona, que foi a escola sob o v\u00e9u do esquecimento.<\/p>\n<p>Estamos tamb\u00e9m nos adaptando ao que vem em mar\u00e7o. O pr\u00f3ximo m\u00eas ser\u00e1 marcante em termos de energias. O que se pode saber at\u00e9 aqui, \u00e9 que devemos ficar atentos aos dias 3, 8 e 9. Teremos ali ondas bastante fortes de mais Luz.<\/p>\n<p>Mas tudo isso \u00e9 maravilhoso, apesar dos sintomas. Os nossos corpos est\u00e3o sendo adaptados para as energias de Quinta Dimens\u00e3o. Esses sintomas, na medida que nos ajustamos, desaparecem.<\/p>\n<p>Tamb\u00e9m \u00e9 esperado algo grandioso para os dias em torno de 21-03 (Equin\u00f3cio). Pelas informa\u00e7\u00f5es antecipadas, haver\u00e1 mais uma grande onda de despertar de consci\u00eancias.<\/p>\n<p>Na medida que as informa\u00e7\u00f5es chegam mais detalhadamente, passarei para voc\u00eas aqui. Essa onda de 21-03 est\u00e1 diretamente relacionada com a medita\u00e7\u00e3o de 21-01.<\/p>\n<p>Importantes acontecimentos est\u00e3o na fila para serem apresentados \u00e0 humanidade. Nem todos perceber\u00e3o. Por\u00e9m, voc\u00ea que est\u00e1 desperto ou despertando, saber\u00e1 identific\u00e1-los.<\/p>\n<p>Bons ausp\u00edcios surgem no horizonte! Isso nos alegra profundamente!<\/p>\n<p>Eu sou Vital Frosi e minha miss\u00e3o \u00e9 o esclarecimento.<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 528<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>Amados! Estamos entrando cada vez mais na profundidade da Luz plena. \u00c9 tanta energia fot\u00f4nica enviada em dire\u00e7\u00e3o \u00e0 Terra, desde 2012, que est\u00e3o vindo em forma de ondas intermitentes. Caso essa energia viesse toda de uma vez vez s\u00f3, ser\u00edamos pulverizados instantaneamente. Mas o Universo \u00e9 s\u00e1bio e tem suas Leis pr\u00f3prias que rege [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-15642","post","type-post","status-publish","format-standard","hentry","category-espiritualidade"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/15642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=15642"}],"version-history":[{"count":0,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/15642\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=15642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=15642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=15642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}