{"id":16753,"date":"2020-08-31T02:50:36","date_gmt":"2020-08-31T02:50:36","guid":{"rendered":"https:\/\/espacodosol.com\/blog.br\/?p=16753"},"modified":"2020-08-31T02:50:36","modified_gmt":"2020-08-31T02:50:36","slug":"tratamento-da-covid-19-cientista-encontra-ponto-fraco-do-coronavirus-que-pode-servir-para-neutraliza-lo","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2020\/08\/31\/tratamento-da-covid-19-cientista-encontra-ponto-fraco-do-coronavirus-que-pode-servir-para-neutraliza-lo\/","title":{"rendered":"Tratamento da covid-19: cientista encontra &#8216;ponto fraco&#8217; do coronav\u00edrus, que pode servir para neutraliz\u00e1-lo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16754\" src=\"https:\/\/espacodosol.com\/blog.br\/wp-content\/uploads\/2020\/08\/covid_fisica.jpg\" alt=\"\" width=\"660\" height=\"371\" \/><\/p>\n<p class=\"story-body__introduction\" style=\"text-align: justify;\">A f\u00edsica mexicana M\u00f3nica Olvera teve sua \u00e1rea de pesquisas profundamente alterada por causa da pandemia do coronav\u00edrus.<\/p>\n<p style=\"text-align: justify;\">Seu irm\u00e3o ficou gravemente doente no M\u00e9xico, o que levou a cientista a concentrar seus estudos na compreens\u00e3o de como o v\u00edrus Sars-CoV-2, que causa a covid-19, interage com o corpo humano em um n\u00edvel f\u00edsico-biol\u00f3gico.<\/p>\n<p style=\"text-align: justify;\">&#8220;N\u00e3o tenho nada a ver com medicina. Sou uma cientista focada em ci\u00eancia dos materiais. Mas quando vimos esse problema t\u00e3o forte, entramos em a\u00e7\u00e3o&#8221;, disse ela \u00e0 BBC News Mundo (servi\u00e7o em espanhol da BBC).<\/p>\n<p style=\"text-align: justify;\">Sua equipe da Northwestern University, nos EUA, analisou as diferen\u00e7as entre o coronav\u00edrus que causou a epidemia de Sars em 2003 e o que causa a covid-19. E encontrou um ponto fraco no qual o v\u00edrus pode ser atacado.<\/p>\n<p style=\"text-align: justify;\">&#8220;Estamos bloqueando o v\u00edrus&#8221;, diz ela, explicando como seu experimento a n\u00edvel molecular inicialmente reduziu a conex\u00e3o do pat\u00f3geno aos receptores humanos em 30%.<\/p>\n<p style=\"text-align: justify;\">&#8220;Antes do v\u00edrus entrar (nas mol\u00e9culas do corpo), podemos atac\u00e1-lo para que ele n\u00e3o tenha mais tanta energia de atra\u00e7\u00e3o, que n\u00e3o seja capaz de infectar. E, se entrar, que fique bloqueado ali&#8221;, explica a cientista.<\/p>\n<p style=\"text-align: justify;\">&#8220;\u00c9 outra forma de cura. N\u00e3o s\u00e3o anticorpos [como os das vacinas], aos quais os v\u00edrus podem ser tornar resistentes. S\u00e3o muitos os casos em que os v\u00edrus se tornam resistentes aos anticorpos&#8221;, acrescenta.<\/p>\n<p style=\"text-align: justify;\">Em tr\u00eas meses, Olvera espera projetar um pol\u00edmero \u2014 um composto qu\u00edmico \u2014 que triplicar\u00e1 a efic\u00e1cia do bloqueio e se tornar\u00e1 uma forma de proteger o corpo do Sars-CoV-2. O desafio ser\u00e1 testar se esse composto funciona ap\u00f3s ser metabolizado pelo corpo \u2014 atualmente as pesquisas foram feitas apenas em laborat\u00f3rio.<\/p>\n<figure class=\"media-landscape has-caption full-width\" style=\"text-align: justify;\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/12C61\/production\/_113979867_1bddef62-a185-48ee-aa20-f9d73ad856a0.jpg\" alt=\"M\u00f3nica Olvera de la Cruz\" width=\"549\" height=\"549\" data-highest-encountered-width=\"624\" \/><span class=\"off-screen\">Direito de imagem<\/span><span class=\"story-image-copyright\">M\u00d3NICA OLVERA\/NORTHWESTERN UNIVERSITY<\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span><span class=\"media-caption__text\">A pesquisadora M\u00f3nica Olvera realiza seu estudo nos Estados Unidos<\/span><\/figcaption><\/figure>\n<h2 class=\"story-body__crosshead\" style=\"text-align: justify;\">Qual foi a descoberta?<\/h2>\n<p style=\"text-align: justify;\">O Sars-CoV-2 entra no corpo por meio de suas prote\u00ednas S, que entram em contato com a enzima conversora de angiotensina (AC2) das c\u00e9lulas humanas.<\/p>\n<p style=\"text-align: justify;\">As enzimas AC2 tamb\u00e9m est\u00e3o presentes nas c\u00e9lulas do cora\u00e7\u00e3o, do est\u00f4mago, dos rins, &#8220;ent\u00e3o, quando algu\u00e9m est\u00e1 infectado (com o v\u00edrus Sars-CoV-2, ele) pode danificar essas c\u00e9lulas&#8221;, explica Olvera.<\/p>\n<p style=\"text-align: justify;\">Seu estudo, feito em colabora\u00e7\u00e3o com o pesquisador Baofu Qiao, detectou que o Sars-CoV-2 faz as conex\u00f5es com c\u00e9lulas humanas a partir de cargas positivas na prote\u00edna das esp\u00edculas (protuber\u00e2ncias em sua superf\u00edcie que se assemelham a pequenos espinhos e formam uma coroa) e que essas cargas podem ser bloqueadas.<\/p>\n<p style=\"text-align: justify;\">&#8220;A energia de atra\u00e7\u00e3o entre aquele grupo que est\u00e1 nas esp\u00edculas e as c\u00e9lulas epiteliais era mais fraca no primeiro coronav\u00edrus do que no Sars-CoV-2&#8221;, explica Olvera.<\/p>\n<p style=\"text-align: justify;\">&#8220;Percebemos que se modific\u00e1ssemos as cargas do novo coronav\u00edrus, a atra\u00e7\u00e3o com o receptor diminu\u00eda muito&#8221;, acrescenta.<\/p>\n<p style=\"text-align: justify;\">O trabalho de bloqueio ocorreu em um dos tr\u00eas grupos da prote\u00edna das esp\u00edculas, o que reduziu em 30% a capacidade do v\u00edrus de se conectar com o receptor das c\u00e9lulas do corpo.<\/p>\n<p style=\"text-align: justify;\">Se os pesquisadores conseguirem obter um pol\u00edmero que bloqueie os tr\u00eas grupos da prote\u00edna, o resultado pode triplicar e fazer com que o novo coronav\u00edrus tenha pouqu\u00edssimas oportunidades de atacar o corpo.<\/p>\n<p style=\"text-align: justify;\">&#8220;Quero fazer um projeto que ataque a todos. \u00c9 muito complicado, \u00e9 um projeto dif\u00edcil. Mas a ideia \u00e9 (ter) um projeto que funcione e seja testado em laborat\u00f3rio&#8221;, diz a cientista.<\/p>\n<figure class=\"media-landscape has-caption full-width\" style=\"text-align: justify;\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/1311C\/production\/_113980187_gettyimages-1227507040.jpg\" alt=\"Ilustra\u00e7\u00e3o do sars-cov-2 atacando uma c\u00e9lula\" width=\"976\" height=\"549\" data-highest-encountered-width=\"624\" \/><span class=\"off-screen\">Direito de imagem<\/span><span class=\"story-image-copyright\">GETTY IMAGES<\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span><span class=\"media-caption__text\">As esp\u00edculas do coronav\u00edrus s\u00e3o pequenos espinhos que formam sua &#8216;coroa&#8217;<\/span><\/figcaption><\/figure>\n<h2 class=\"story-body__crosshead\" style=\"text-align: justify;\">Como isso pode ser usado na medicina?<\/h2>\n<p style=\"text-align: justify;\">O processo de cria\u00e7\u00e3o de um pol\u00edmero que atue contra as esp\u00edculas do Sars-CoV-2 pode levar de dois a tr\u00eas meses.<\/p>\n<p style=\"text-align: justify;\">Uma vez criado, ser\u00e1 preciso encontrar um meio adequado de administr\u00e1-lo. Olvera acredita que poderia funcionar por meio de um aerossol.<\/p>\n<p style=\"text-align: justify;\">Mas ela alerta que &#8220;os v\u00edrus s\u00e3o tremendos; podem usar os caps\u00eddeos [estruturas] de outros v\u00edrus e RNA, duplicar-se e sofrer muta\u00e7\u00e3o&#8221;.<\/p>\n<p style=\"text-align: justify;\">E um dos problemas enfrentados pelos v\u00e1rios pa\u00edses e equipes que correm contra o tempo para encontrar uma vacina \u00e9 justamente com os anticorpos que elas geram e sua efic\u00e1cia diante das muta\u00e7\u00f5es do Sars-CoV-2.<\/p>\n<p style=\"text-align: justify;\">&#8220;Queremos criar algo que n\u00e3o seja biol\u00f3gico, que n\u00e3o crie resist\u00eancia. Evitar que o v\u00edrus encontre outras formas de progredir. Acreditamos que pode ser uma forma de enfraquecer o v\u00edrus, diferente do que est\u00e1 sendo feito&#8221;, completa.<\/p>\n<p style=\"text-align: justify;\">Se as muta\u00e7\u00f5es mantiverem os mesmos grupos de componentes para atrair c\u00e9lulas receptoras do corpo, o rem\u00e9dio seguiria funcionando.<\/p>\n<p style=\"text-align: justify;\">\u00c9 curioso que uma abordagem feita por um outro \u00e2ngulo cient\u00edfico \u2014 no caso de Olvera, o da f\u00edsica \u2014 possa oferecer uma solu\u00e7\u00e3o promissoras para a pandemia. Mas para a pesquisadora, isso pouco importa neste momento.<\/p>\n<p style=\"text-align: justify;\">&#8220;Estamos todos de alguma forma envolvidos com isso, \u00e9 um problema global. E n\u00e3o existe melhor maneira de resolver do que todos os cientistas trabalharem juntos nisso&#8221;, diz Olvera.<\/p>\n<p>Fonte: <span class=\"byline__name\">Dar\u00edo Brooks &#8211; <\/span><span class=\"byline__title\">BBC News Mundo<\/span><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 566<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>A f\u00edsica mexicana M\u00f3nica Olvera teve sua \u00e1rea de pesquisas profundamente alterada por causa da pandemia do coronav\u00edrus. Seu irm\u00e3o ficou gravemente doente no M\u00e9xico, o que levou a cientista a concentrar seus estudos na compreens\u00e3o de como o v\u00edrus Sars-CoV-2, que causa a covid-19, interage com o corpo humano em um n\u00edvel f\u00edsico-biol\u00f3gico. &#8220;N\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-16753","post","type-post","status-publish","format-standard","hentry","category-saude"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=16753"}],"version-history":[{"count":0,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16753\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=16753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=16753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=16753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}