{"id":16762,"date":"2020-09-04T02:17:54","date_gmt":"2020-09-04T02:17:54","guid":{"rendered":"https:\/\/espacodosol.com\/blog.br\/?p=16762"},"modified":"2020-09-04T02:17:54","modified_gmt":"2020-09-04T02:17:54","slug":"cistite-combata-com-esta-alternativa-natural","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2020\/09\/04\/cistite-combata-com-esta-alternativa-natural\/","title":{"rendered":"Cistite: Combata com Esta Alternativa Natural"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16763\" src=\"https:\/\/espacodosol.com\/blog.br\/wp-content\/uploads\/2020\/09\/cistite.jpg\" alt=\"\" width=\"300\" height=\"300\" \/><\/p>\n<p style=\"text-align: justify;\">A cistite atinge mulheres de todas as idades, mais frequente nas que est\u00e3o no in\u00edcio da vida sexual, as que t\u00eam rela\u00e7\u00f5es frequentes e at\u00e9 na menopausa.<\/p>\n<p style=\"text-align: justify;\">Ao longo da vida, cerca de metade das mulheres s\u00e3o acometidas com essas infec\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Pela pr\u00f3pria anatomia da mulher, j\u00e1 h\u00e1 uma condi\u00e7\u00e3o de maior suscetibilidade desse tipo de infec\u00e7\u00e3o do trato urin\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>As mulheres apresentam uma uretra mais curta do que os homens, tornando-a mais propensa a infec\u00e7\u00e3o.<\/li>\n<li>Os homens tem mais um fator favor\u00e1vel, que \u00e9 a presen\u00e7a de um inibidor de crescimento bacteriano liberado pela pr\u00f3stata.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Essa condi\u00e7\u00e3o chamada de cistite da lua de mel, pode ser evit\u00e1vel de forma natural.<\/p>\n<p style=\"text-align: justify;\">Para isso, se indica o cranberry na forma de suco, que mostra benef\u00edcios bem divulgados. Por\u00e9m, n\u00e3o se leva em considera\u00e7\u00e3o que esses sucos s\u00e3o carregados com frutose, causando um desequil\u00edbrio na flora intestinal.<\/p>\n<p style=\"text-align: justify;\">Consequentemente, se ganha de um lado, mas se perde do outro: melhora-se a sa\u00fade urin\u00e1ria, mas compromete-se a sensibilidade \u00e0 insulina. H\u00e1 tamb\u00e9m aumento de \u00e1cido \u00farico, associado a outras manifesta\u00e7\u00f5es negativas de sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">Mas ainda h\u00e1 boas not\u00edcias naturais em rela\u00e7\u00e3o \u00e0 cistite:<\/p>\n<p style=\"text-align: justify;\">\u00c9 a D-Mannose, o ingrediente ativo do suco de cranberry, que pode ser usado preventivamente ou at\u00e9 terapeuticamente para melhorar o sistema urin\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">Ela \u00e9 10-50 vezes mais forte que o cranberry, n\u00e3o-t\u00f3xica e completamente segura, sem efeitos adversos.<\/p>\n<p style=\"text-align: justify;\">Grande parte da D-Mannose \u00e9 filtrada pelos rins e encaminhada para a bexiga, sendo rapidamente excretada na urina.<\/p>\n<p style=\"text-align: justify;\">D-Mannose colabora na nutri\u00e7\u00e3o da sua flora do trato urin\u00e1rio, n\u00e3o afetando as bact\u00e9rias boas.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, quando voc\u00ea toma antibi\u00f3ticos para uma infec\u00e7\u00e3o do trato urin\u00e1rio (UTI), a a\u00e7\u00e3o n\u00e3o \u00e9 seletiva, pois matam as bact\u00e9rias boas e ruins.<\/p>\n<p style=\"text-align: justify;\">Isso predisp\u00f5e o aparecimento de infec\u00e7\u00f5es secund\u00e1rias por fungos e problemas digestivos, por disbiose intestinal.<\/p>\n<h2 style=\"text-align: justify;\">Como a D-Mannose combate a infec\u00e7\u00e3o do trato urin\u00e1rio (ITU)?<\/h2>\n<p style=\"text-align: justify;\">Cerca de 90% de todas as ITUs, como a cistite, s\u00e3o causadas por Escherichia coli (E. coli), que normalmente \u00e9 encontrada no trato intestinal.<\/p>\n<p style=\"text-align: justify;\">Por lapsos de higiene, essas bact\u00e9rias v\u00e3o para o lugar errado, no caso o trato urin\u00e1rio, e a\u00ed se multiplicam.<\/p>\n<p style=\"text-align: justify;\">\u00c9 quando come\u00e7am os problemas e o surgimento de sinais e sintomas como:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Dor em queima\u00e7\u00e3o com a mic\u00e7\u00e3o<\/li>\n<li>Necessidades frequentes de urinar<\/li>\n<li>Dor abdominal baixa<\/li>\n<li>Sangue na sua urina (eventualmente)<\/li>\n<li>Urina turva e com odor<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Teoricamente, as bact\u00e9rias que est\u00e3o no trato urin\u00e1rio, deveriam ser expulsas com a mic\u00e7\u00e3o. Por\u00e9m, no caso da E. coli isso n\u00e3o ocorre, j\u00e1 que ela apresenta parede celular coberta de f\u00edmbrias, proje\u00e7\u00f5es finas que permitem que estas grudem nas paredes internas da bexiga e cheguem a subir at\u00e9 o ureter e os rins.<\/p>\n<p style=\"text-align: justify;\">Essas pequenas proje\u00e7\u00f5es de dedos s\u00e3o feitas de um complexo amino\u00e1cido-a\u00e7\u00facar, uma glicoprote\u00edna chamada lectina, que as torna pegajosas.<\/p>\n<p style=\"text-align: justify;\">A lectina na f\u00edmbria das bact\u00e9rias liga-se \u00e0 D-Mannose, que \u00e9 produzida pelas c\u00e9lulas e cobre o revestimento interno dos seus \u00f3rg\u00e3os urin\u00e1rios. Essa D-Mannose permite que as bact\u00e9rias \u201cgrudem\u201d em voc\u00ea \u2013 como o velcro.<\/p>\n<p style=\"text-align: justify;\">As poucas E. coli deixadas grudadas a mol\u00e9culas de D-Mannose nas c\u00e9lulas tornam-se presas f\u00e1ceis para os gl\u00f3bulos brancos e outros agentes do sistema imunol\u00f3gico.<\/p>\n<p style=\"text-align: justify;\">Deve-se notar que esta n\u00e3o \u00e9 a mesma E. coli associada a surtos de morte em plantas insalubres de processamento de alimentos \u2013 que \u00e9 uma variedade mutante, provavelmente criada pelo uso excessivo de antibi\u00f3ticos<\/p>\n<h2 style=\"text-align: justify;\">Atitude importante<\/h2>\n<p style=\"text-align: justify;\">Na presen\u00e7a destas queixas urin\u00e1rias \u00e9 importante procurar o quanto antes o seu m\u00e9dico para que ele tome as provid\u00eancias necess\u00e1rias.<\/p>\n<p style=\"text-align: justify;\">As infec\u00e7\u00f5es do trato urin\u00e1rio inferior s\u00e3o as mais comuns, como a cistite (bexiga) e a uretrite (uretra), que podem evoluir para nefrite ou pielonefrite (rins).<\/p>\n<p style=\"text-align: justify;\">As infec\u00e7\u00f5es renais podem causar danos permanentes nos rins e insufici\u00eancia renal se n\u00e3o forem prontamente resolvidas.<\/p>\n<h2 style=\"text-align: justify;\">Como reconhecer sintomas de uma infec\u00e7\u00e3o renal<\/h2>\n<p style=\"text-align: justify;\">Al\u00e9m das queixas cl\u00e1ssicas j\u00e1 mencionadas no in\u00edcio do texto, pode ocorrer ainda:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Febre<\/li>\n<li>Dor nas costas, lateral (flanco) ou na virilha<\/li>\n<li>Dor abdominal<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sempre que fizer uso de um antibi\u00f3tico \u00e9 importante associar probi\u00f3ticos de alta pot\u00eancia, que deve ser ingerido em hora diferente do antibi\u00f3tico.<\/p>\n<h2 style=\"text-align: justify;\">Medidas preventivas para evitar infec\u00e7\u00e3o do trato urin\u00e1rio<\/h2>\n<p style=\"text-align: justify;\">Para mulher, aconselha-se:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Beba muita \u00e1gua pura e filtrada todos os dias.<\/li>\n<li>N\u00e3o segurar a urina. Respeite o impulso.<\/li>\n<li>Limpe-se de frente para tr\u00e1s para impedir que as bact\u00e9rias entrem na sua uretra.<\/li>\n<li>Prefira banho de chuveiros em vez de banheiras, hidromassagem e jacuzzis.<\/li>\n<li>Limpe sua \u00e1rea genital antes da rela\u00e7\u00e3o sexual.<\/li>\n<li>Use apenas papel higi\u00eanico sem perfume branco para evitar poss\u00edveis rea\u00e7\u00f5es al\u00e9rgicas. Prefira o bid\u00ea.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Manter uma dieta saud\u00e1vel \u00e9 fundamental no apoio ao seu trato urin\u00e1rio, consumindo produtos fermentados como kefir, chucrute e outros vegetais fermentados, al\u00e9m de suplementos probi\u00f3ticos.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Refer\u00eancias bibliogr\u00e1ficas:<\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Urol Res, 1983;11:97-102<\/em><\/li>\n<li><em>American Family Physician, August 1991;579-586<\/em><\/li>\n<li><em>Age Aging, 2000;29:9-12<\/em><\/li>\n<li><em>Am Fam Physician, December 1, 2004;70(11):2175-2177<\/em><\/li>\n<li><em>Nutra Ingredients June 1, 2010<\/em><\/li>\n<li><em>Western Journal of Medicine, Management of uncomplicated urinary tract infections, January 2002<\/em><\/li>\n<li><em>Tahoma Clinic Blog, D-Mannose for Bladder and Kidney Infections<\/em><\/li>\n<\/ul>\n<p>Fonte: https:\/\/www.drrondo.com\/<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 599<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>A cistite atinge mulheres de todas as idades, mais frequente nas que est\u00e3o no in\u00edcio da vida sexual, as que t\u00eam rela\u00e7\u00f5es frequentes e at\u00e9 na menopausa. Ao longo da vida, cerca de metade das mulheres s\u00e3o acometidas com essas infec\u00e7\u00f5es. Pela pr\u00f3pria anatomia da mulher, j\u00e1 h\u00e1 uma condi\u00e7\u00e3o de maior suscetibilidade desse tipo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-16762","post","type-post","status-publish","format-standard","hentry","category-saude"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=16762"}],"version-history":[{"count":0,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16762\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=16762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=16762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=16762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}