{"id":16878,"date":"2020-10-20T02:46:51","date_gmt":"2020-10-20T02:46:51","guid":{"rendered":"https:\/\/espacodosol.com\/blog.br\/?p=16878"},"modified":"2020-10-20T02:46:51","modified_gmt":"2020-10-20T02:46:51","slug":"os-seis-eus-fisico-mental-emocional-espiritual-transcendental-cosmico","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2020\/10\/20\/os-seis-eus-fisico-mental-emocional-espiritual-transcendental-cosmico\/","title":{"rendered":"Os Seis Eus &#8211; F\u00edsico Mental Emocional Espiritual Transcendental C\u00f3smico"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-16879\" src=\"https:\/\/espacodosol.com\/blog.br\/wp-content\/uploads\/2020\/10\/The-Six-Selves-Cover-2.jpg\" alt=\"\" width=\"489\" height=\"288\" \/><\/p>\n<p style=\"text-align: justify;\">Os Seis Eus<\/p>\n<p style=\"text-align: justify;\">Os Seis Eus<\/p>\n<p style=\"text-align: justify;\">Os Seis Eus. Por Dr. Schavi M. Ali<\/p>\n<p style=\"text-align: justify;\">Somos formados por seis \u201cEus\u201d: F\u00cdSICO, MENTAL, EMOCIONAL, ESPIRITUAL, TRANSCENDENTAL e C\u00d3SMICO.<\/p>\n<p style=\"text-align: justify;\">Este \u00e9 um conhecimento antigo registrado h\u00e1 milhares de anos em numerosos textos sagrados revelados a muitas culturas.<\/p>\n<p style=\"text-align: justify;\">O &#8220;Eu F\u00edsico&#8221; \u00e9 o nosso ser material que \u00e9 gerado nos m\u00fasculos, gl\u00e2ndulas, \u00f3rg\u00e3os, tecidos, veias, art\u00e9rias, c\u00e9lulas, meridianos, mol\u00e9culas, \u00e1tomos, part\u00edculas subat\u00f4micas, etc. &#8211; tudo o que podemos ver de n\u00f3s mesmos e outros ou que \u00e0s vezes podem ser vistos sob um microsc\u00f3pio ou por ex-raios.<\/p>\n<p style=\"text-align: justify;\">O &#8220;Eu Mental&#8221; cont\u00e9m as imagens que concebemos no c\u00e9rebro (que tem uma frequ\u00eancia el\u00e9trica) com base em v\u00e1rias experi\u00eancias que s\u00e3o vistas, ouvidas, sentidas ou sentidas (como quando &#8220;sentimos&#8221; uma fragr\u00e2ncia) &#8211; a parte de n\u00f3s que pode intelectualizar informa\u00e7\u00f5es ou pensar sobre situa\u00e7\u00f5es passadas ou atuais e fazer sentido delas com base em nossas percep\u00e7\u00f5es dos pr\u00f3prios eventos.<\/p>\n<p style=\"text-align: justify;\">O \u201cEu Emocional\u201d s\u00e3o os nossos sentimentos (que t\u00eam uma frequ\u00eancia magn\u00e9tica) que geralmente ocorrem quando temos uma experi\u00eancia f\u00edsica e ent\u00e3o temos uma percep\u00e7\u00e3o mental sobre ela.<\/p>\n<p style=\"text-align: justify;\">\u00a0Os Seis Eus &#8211; Todos Nossos Eus<\/p>\n<p style=\"text-align: justify;\">Todos n\u00f3s mesmos<\/p>\n<p style=\"text-align: justify;\">Os Seis Eus<\/p>\n<p style=\"text-align: justify;\">\u00a0Consequentemente, pensamentos e sentimentos somados tornam-se percep\u00e7\u00f5es e cren\u00e7as.<\/p>\n<p style=\"text-align: justify;\">O &#8220;Eu Espiritual&#8221; \u00e9 a nossa for\u00e7a vital &#8211; a pr\u00f3pria energia da FONTE que corre atrav\u00e9s de n\u00f3s &#8211; que misticamente nos conecta \u00e0 f\u00e9 em um PODER SUPERIOR ou um ABSOLUTO DIVINO a partir do qual tudo \u00e9 criado em cada planeta, em cada gal\u00e1xia, em cada universo , em todo o cosmos &#8211; aquela parte de n\u00f3s que podemos acenar e honrar em v\u00e1rios rituais, como ora\u00e7\u00e3o e medita\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O &#8220;Eu Transcendental&#8221; \u00e9 aquele que eleva acima de densos pensamentos, emo\u00e7\u00f5es e padr\u00f5es de comportamento &#8220;3d&#8221; para que possamos nos comunicar com nosso EU SUPERIOR &#8211; nossa ALMA &#8211; nossa super consci\u00eancia e, portanto, ter um relacionamento mais pr\u00f3ximo com o &#8221; Auto&#8221;.<\/p>\n<p style=\"text-align: justify;\">O &#8220;Eu C\u00f3smico&#8221; \u00e9 composto de muitas experi\u00eancias e consequentes vidas volumosas e os continuums espa\u00e7o \/ tempo que eles cont\u00eam, cujas experi\u00eancias s\u00e3o registradas no &#8220;Registro Ak\u00e1shico&#8221; &#8211; a &#8220;biblioteca et\u00e9rea&#8221; simb\u00f3lica que abriga todas as experi\u00eancias de todos os seres sencientes ao longo de eras ou eras de tempo.<\/p>\n<p style=\"text-align: justify;\">Os Seis Eus<\/p>\n<p style=\"text-align: justify;\">Mesmo para aqueles indiv\u00edduos que n\u00e3o acreditam em vidas subsequentes na Terra \/ Gaia (reencarna\u00e7\u00e3o), eles parecem, no entanto, admitir que o Esp\u00edrito e a Alma estavam &#8220;em algum lugar&#8221; em &#8220;algum momento&#8221; e s\u00e3o, portanto, &#8220;Eus&#8221; imortais, mesmo que o fa\u00e7am n\u00e3o entendo profundamente o conceito de vida continuada. Algumas pessoas realmente acreditam que habitamos muitos planetas, gal\u00e1xias e universos em um ritmo cont\u00ednuo de vida Divina.<\/p>\n<p style=\"text-align: justify;\">Aqui eles podem at\u00e9 mesmo aplicar o conceito de que a energia n\u00e3o pode ser produzida ou destru\u00edda (pelo menos n\u00e3o pela humanidade); ele s\u00f3 pode ser transformado, e as transforma\u00e7\u00f5es s\u00e3o eternas.<\/p>\n<p style=\"text-align: justify;\">Todos os nossos \u201cEus\u201d e todas as no\u00e7\u00f5es deles est\u00e3o sendo deslocados, ajustados e transformados e recebendo tremendas frequ\u00eancias de LUZ.<\/p>\n<p style=\"text-align: justify;\">Mesmo a ci\u00eancia tradicional, em particular no tema de estudo conhecido como \u201cF\u00edsica\u201d, est\u00e1 se comunicando sobre o brilho maior que est\u00e1 sendo visto em toda a gal\u00e1xia e o brilho que cada planeta parece emitir para o cosmos.<\/p>\n<p style=\"text-align: justify;\">Mais discuss\u00f5es sobre o \u201cCintur\u00e3o de F\u00f3tons\u201d e o \u201cGrande Sol Central\u201d est\u00e3o ocorrendo, e padr\u00f5es est\u00e3o sendo realizados nos muitos eventos c\u00f3smicos que acontecem diariamente.<\/p>\n<p style=\"text-align: justify;\">Por exemplo, a cada onze anos, aparentemente de acordo com o cronograma, ocorre um \u201cM\u00ednimo Solar\u201d ou um \u201cM\u00e1ximo Solar\u201d. Na primeira situa\u00e7\u00e3o, as explos\u00f5es solares (libera\u00e7\u00e3o de f\u00f3tons, el\u00e9trons, gases de di\u00f3xido de carbono, etc.) tornam-se gradualmente mais fracas e ent\u00e3o n\u00e3o ocorrem de forma alguma.<\/p>\n<p style=\"text-align: justify;\">Na \u00faltima situa\u00e7\u00e3o, onze anos depois, as chamas se intensificam (como est\u00e3o fazendo agora) e enviam uma poderosa energia que varre os raios gama potencialmente nocivos sendo emitidos do espa\u00e7o profundo fora de nosso sistema solar, e esses raios s\u00e3o devidos ao danificando os escudos protetores de nosso Sol e da Terra \/ Gaia por causa do mau uso humano do livre arb\u00edtrio que orquestra certas atividades desarmoniosas (\u00f3dio, guerra, condi\u00e7\u00f5es opressivas, adultera\u00e7\u00e3o da Natureza, etc.).<\/p>\n<p style=\"text-align: justify;\">A FONTE ent\u00e3o envia LUZ amorosa, curativa e reparadora para acalmar e transformar os habitantes da Terra \/ Gaia e \u201cSeus\u201d.<\/p>\n<p style=\"text-align: justify;\">Assim, um tipo de fertiliza\u00e7\u00e3o, gesta\u00e7\u00e3o e, finalmente, um &#8220;renascimento&#8221; ocorre, e nos elevamos para uma &#8220;Nova Idade de Ouro&#8221; &#8211; o &#8220;Sattva Yuga&#8221; (&#8220;Era da Paz&#8221;) dos antigos ensinamentos, como os de as revela\u00e7\u00f5es v\u00e9dicas.<\/p>\n<p style=\"text-align: justify;\">Os Seis Eus &#8211; Nova Idade de Ouro<\/p>\n<p style=\"text-align: justify;\">Nova Idade de Ouro<\/p>\n<p style=\"text-align: justify;\">Os Seis Eus<\/p>\n<p style=\"text-align: justify;\">Os Seis Eus<\/p>\n<p style=\"text-align: justify;\">\u00c9 por isso que muitas culturas antigas se referiam a SOURCE como uma \u201cM\u00e3e Divina\u201d. Na verdade, no estudo da Lingu\u00edstica, descobrimos que existem mais nomes femininos para FONTE do que nomes masculinos.<\/p>\n<p style=\"text-align: justify;\">As eje\u00e7\u00f5es de massa coronal (part\u00edculas de plasma explodindo do Sol) frequentemente seguem as erup\u00e7\u00f5es e t\u00eam seu pr\u00f3prio tipo de frequ\u00eancias de radia\u00e7\u00e3o; entretanto, nos \u00faltimos anos, observou-se que eles surgiram sem que as erup\u00e7\u00f5es ocorressem necessariamente primeiro.<\/p>\n<p style=\"text-align: justify;\">Os ventos solares s\u00e3o outro fen\u00f4meno, e eles tamb\u00e9m auxiliam na remo\u00e7\u00e3o de raios gama potencialmente perigosos, empurrando as Eje\u00e7\u00f5es de Massa Coronal para o espa\u00e7o.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m disso, a Terra \/ Gaia \u00e9 frequentemente banhada pela LUZ das caudas dos cometas ou pelas supernovas que s\u00e3o estrelas explodindo que criam buracos negros que agem como aspiradores de p\u00f3 que sugam qualquer coisa perto deles como se uma nova linha do tempo ou O continuum espa\u00e7o \/ tempo pode ser elevado atrav\u00e9s deles e uma LUZ diferente vista do outro lado.<\/p>\n<p style=\"text-align: justify;\">Na verdade, a \u201cKali Yuga\u201d (\u201cEra do Caos\u201d) pode ser comparada a uma supernova cujo tempo de se abrir para um novo continuum e uma nova LUZ chegou. \u201cKali Yuga\u201d eventualmente dar\u00e1 lugar a \u201cSattva Yuga\u201d e supernova explodindo.<\/p>\n<p style=\"text-align: justify;\">Nossos seis \u201cEus\u201d est\u00e3o todos sendo energizados.<\/p>\n<p style=\"text-align: justify;\">Estamos constantemente sendo ensinados sobre o COSMIC HOLY BOOK e como seus \u201ccap\u00edtulos\u201d e \u201cversos\u201d s\u00e3o mensagens ou projetos para poss\u00edveis experi\u00eancias baseadas em como usamos nosso livre arb\u00edtrio.<\/p>\n<p style=\"text-align: justify;\">No entanto, assim como um projeto arquitet\u00f4nico pode ser redesenhado com base na casa desejada pelo cliente ou nas prefer\u00eancias de constru\u00e7\u00e3o comercial, n\u00f3s tamb\u00e9m estamos sendo &#8220;redesenhados&#8221; ou &#8220;reclimatados&#8221; a um &#8220;Projeto Divino&#8221; original que sempre esteve dispon\u00edvel para n\u00f3s, mas isso teve que ser conscientemente concebido como uma possibilidade enquanto experimentamos este dom\u00ednio planet\u00e1rio particular chamado Terra \/ Gaia.<\/p>\n<p style=\"text-align: justify;\">Os Seis Eus<\/p>\n<p style=\"text-align: justify;\">A an\u00e1lise final de todo o anterior \u00e9 que existe uma INTELIG\u00caNCIA DIVINA, uma FONTE SAGRADA, cuja LUZ \u00e9 poderosa.<\/p>\n<p style=\"text-align: justify;\">Esta PRESEN\u00c7A INFINITA \u201ccriou\u201d e continua a \u201ccriar\u201d a sua CRIA\u00c7\u00c3O! Simplesmente sentamos com um sorriso e esperamos nosso \u201crenascimento\u201d? N\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Ainda devemos ativar nosso livre arb\u00edtrio de forma amorosa e, para isso, devemos ser diligentes em cuidar adequadamente do Eu F\u00edsico, em monitorar cuidadosamente o \u201cEu Mental\u201d, em nutrir o \u201cEu Emocional\u201d, em nos comunicarmos com o \u201cEu Espiritual\u201d, no esfor\u00e7o de elevar-se acima dos acontecimentos densos no planeta que podem perturbar o sistema nervoso e afetar os \u201cEus\u201d F\u00edsicos, Mentais e Emocionais, e devemos reconhecer o Eu C\u00f3smico honrando nossos ancestrais de todos os tempos linha &#8211; os Avatares, S\u00e1bios, Profetas, Devas, Devis, Mestres Ascensionados e tamb\u00e9m os Anjos.<\/p>\n<p style=\"text-align: justify;\">Estamos conectados a todos eles porque estamos e eles est\u00e3o conectados ao TUDO ABSOLUTO &#8211; \u00e0 FONTE.<\/p>\n<p style=\"text-align: justify;\">Nossos \u201cEus\u201d est\u00e3o entrela\u00e7ando LUZES cintilantes com sons l\u00edricos que v\u00eam do passado, tocam no agora e nos d\u00e3o uma vis\u00e3o intuitiva do futuro. Somos muito mais do que nos ensinam tradicionalmente e ainda n\u00e3o somos o que nos tornaremos.<\/p>\n<p style=\"text-align: justify;\">Nossa jornada n\u00e3o tem fim, pois somos linhagens de FONTE.<\/p>\n<p style=\"text-align: justify;\">Somos formados pelos elementos das estrelas!<\/p>\n<p style=\"text-align: justify;\">Somos, portanto, como supernovas de grande LUZ.<\/p>\n<p style=\"text-align: justify;\">Por Disclosure News<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 677<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>Os Seis Eus Os Seis Eus Os Seis Eus. Por Dr. Schavi M. Ali Somos formados por seis \u201cEus\u201d: F\u00cdSICO, MENTAL, EMOCIONAL, ESPIRITUAL, TRANSCENDENTAL e C\u00d3SMICO. Este \u00e9 um conhecimento antigo registrado h\u00e1 milhares de anos em numerosos textos sagrados revelados a muitas culturas. O &#8220;Eu F\u00edsico&#8221; \u00e9 o nosso ser material que \u00e9 gerado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-16878","post","type-post","status-publish","format-standard","hentry","category-espiritualidade"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=16878"}],"version-history":[{"count":0,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16878\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=16878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=16878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=16878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}