{"id":17118,"date":"2021-03-02T02:08:25","date_gmt":"2021-03-02T02:08:25","guid":{"rendered":"https:\/\/espacodosol.com\/blog.br\/?p=17118"},"modified":"2021-03-02T02:08:25","modified_gmt":"2021-03-02T02:08:25","slug":"lua-cheia-em-virgem","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2021\/03\/02\/lua-cheia-em-virgem\/","title":{"rendered":"Lua cheia em virgem"},"content":{"rendered":"<div style=\"text-align: justify;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-17119\" src=\"https:\/\/espacodosol.com\/blog.br\/wp-content\/uploads\/2021\/03\/Lua-cheia-300x171.png\" alt=\"\" width=\"563\" height=\"321\" \/><\/p>\n<p>Amados,<\/p>\n<p>No momento, restaurar a f\u00e9 e a confian\u00e7a \u00e9 vital; se desejarmos continuar no caminho que escolhemos conscientemente e isto pode ser um desafio \u00e0s vezes, conforme progredimos e nos afastamos da matriz.<\/p>\n<p>Numa \u00e9poca em que tudo o que vemos pode parecer ca\u00f3tico, trabalhar na restaura\u00e7\u00e3o da f\u00e9 e da confian\u00e7a em nosso plano de alma \u00fanico, nas For\u00e7as da luz do Universo e em n\u00f3s mesmos, far\u00e1 toda a diferen\u00e7a na tentativa de recuperar o equil\u00edbrio dentro da corrente turbul\u00eancia e infus\u00e3o de medo, pois \u00e9 o que est\u00e1 literalmente acontecendo, como mais uma t\u00e1tica desesperada das for\u00e7as inferiores, em sua tentativa de manipular e controlar um Planeta que j\u00e1 est\u00e1 bem desperto e se dirigindo para um novo espa\u00e7o harm\u00f4nico.<\/p>\n<p>Neste momento temos muitos alinhamentos planet\u00e1rios, como muitos planetas residindo em Peixes, e uma Lua em Virgem, que como voc\u00ea sabe, \u00e9 tudo sobre limpeza e purifica\u00e7\u00e3o, que nos ajuda a continuar tendo f\u00e9 enquanto trabalhamos na dissolu\u00e7\u00e3o do medo, toxicidade mental, bem como muitos outros programas que foram profundamente implantados em nossas mentes e que devemos agora apagar, se desejamos nos esvaziar de toda a desordem do passado e recuperar nossa verdadeira Ess\u00eancia Iluminada e, portanto, sabedoria.<\/p>\n<p>Agora \u00e9 o momento, especialmente com Virgem e Peixes, para nos comunicarmos com nosso Eu Unificado e come\u00e7ar o processo de unifica\u00e7\u00e3o de ambos, pois \u00e9 fundamental que permane\u00e7amos aterrados, ao mesmo tempo que tamb\u00e9m almejamos o Aspecto Iluminado de quem n\u00f3s somos. \u00c9 importante encontrar o equil\u00edbrio entre os dois planos, ao inv\u00e9s de residir apenas nos mundos et\u00e9reos ou em nosso tang\u00edvel, pois ent\u00e3o cairemos em armadilhas delirantes que nos impedem de estarmos totalmente equilibrados e ancorar nossa Ess\u00eancia Divina e sua Sabedoria no f\u00edsico.<\/p>\n<p>Virgem \u00e9 um signo de terra, ao contr\u00e1rio de Peixes, no entanto tamb\u00e9m \u00e9 mut\u00e1vel, e que tem em comum com Peixes o fato de ambos serem flex\u00edveis e devotados ao servi\u00e7o, e para isso \u00e9 preciso estar aberto \u00e0 mudan\u00e7a em todas as suas formas. As energias de Virgem chegam justamente em um momento em que o Planeta, assim como n\u00f3s, experimentamos uma limpeza profunda, que \u00e9 a principal Ess\u00eancia de Virgem, para nos ajudar a permanecer na pureza de nossa alma e no amor que n\u00f3s somos.<\/p>\n<p>O terreno signo de Virgem, que \u00e9 regido por Merc\u00fario, est\u00e1 associado ao Arqu\u00e9tipo da Virgem, que n\u00e3o est\u00e1 de forma alguma relacionado ao celibato. Pelo contr\u00e1rio, diz respeito ao Arqu\u00e9tipo Feminino Divino de sabedoria, pureza e totalidade \u2013 nutrindo e amando tudo que ela toca; no f\u00edsico. Virgem \u00e9 quem nos lembra que estamos aqui para descer e incorporar a Ess\u00eancia de quem realmente somos na natureza da terra, assim como os desejos de nossa alma.<\/p>\n<p>O aterramento \u00e9 de extrema import\u00e2ncia, j\u00e1 que vai al\u00e9m do nosso bem-estar pessoal. Nosso campo energ\u00e9tico humano est\u00e1 interconectado com o campo planet\u00e1rio, pois como voc\u00eas sabem, somos todos Uma consci\u00eancia viva sob a ilus\u00e3o da separa\u00e7\u00e3o. Quando n\u00e3o estamos aterrados, criamos temporariamente uma obstru\u00e7\u00e3o em nossos canais de campo energ\u00e9tico, impedindo a comunica\u00e7\u00e3o natural com o campo e as grades planet\u00e1rias. Isso \u00e9 principalmente o que cria a sensa\u00e7\u00e3o de isolamento que muitos t\u00eam da Terra e fomenta a ilus\u00e3o mental.<\/p>\n<p>Peixes e Virgem, bem como as muitas outras for\u00e7as da luz fora de nosso Universo que est\u00e3o nos ajudando neste momento, trar\u00e3o consci\u00eancia e o foco correto sobre o que precisamos purificar e limpar para que possamos passar a incorporar a miss\u00e3o de nossa alma. Virgem \u00e9 o signo de purifica\u00e7\u00e3o por excel\u00eancia. \u00c9 com este signo que destilamos o que \u00e9 t\u00f3xico para o f\u00edsico, com o elemento terra, e corpos n\u00e3o f\u00edsicos, pelo uso adequado de energias sutis e ferramentas de limpeza que nos ajudam a equilibr\u00e1-los.<\/p>\n<p>Limpando antigos padr\u00f5es de relacionamentos, trabalhando com a integra\u00e7\u00e3o de polaridades, e para aqueles que est\u00e3o prontos, com a expans\u00e3o de nossas habilidades de cura tamb\u00e9m, pois \u00e9 um tempo para aqueles que passaram de seu despertar para suas fases iniciais de ascens\u00e3o, para iniciar o processo de integra\u00e7\u00e3o da miss\u00e3o de alma, que depende de quanto nos dedicamos para limpar e curar a n\u00f3s mesmos, pois \u00e9 sobre a libera\u00e7\u00e3o de velhas camadas de nosso eu eg\u00f3ico que recuperamos a sabedoria e, portanto, a orienta\u00e7\u00e3o adequada necess\u00e1ria sobre o prop\u00f3sito de nossa alma e habilidades \u00fanicas.<\/p>\n<p>O processo de ascens\u00e3o natural enquanto ainda estamos em nossos corpos f\u00edsicos \u00e9 feito precisamente pela purifica\u00e7\u00e3o de n\u00f3s mesmos, em todos os n\u00edveis, e agora temos um momento de b\u00ean\u00e7\u00e3o para trabalharmos com isso, para que nosso puro Eu Iluminado possa emergir novamente das muitas ilus\u00f5es humanas e disfarces que criamos para ele.<\/p>\n<p>Todos eles necess\u00e1rios para vivenciarmos um plano humano que nos fornece as li\u00e7\u00f5es e experi\u00eancias certas para nos ajudar a lembrar nossa natureza e miss\u00e3o aut\u00eanticas, que \u00e9 o que nos faz evoluir e lembrar nossa ess\u00eancia compassiva.<\/p>\n<p>Agora, mais do que nunca, precisamos nos concentrar em recuperar nossas habilidades e Ess\u00eancia \u00fanicas, para sermos capazes de continuar ajudando, em vez de cair na falsa cren\u00e7a implantada de que tudo est\u00e1 caminhando para um lugar escuro. Quando comungamos com nossa alma para obter orienta\u00e7\u00e3o aut\u00eantica e foco no que desejamos construir e na Luz que nos guia, n\u00e3o h\u00e1 for\u00e7a oposta que possa derrotar nossa inten\u00e7\u00e3o pura de continuar ajudando na transi\u00e7\u00e3o atual.<\/p>\n<p>\u00c9 essa Luz Interior que devemos buscar em nossos momentos mais sombrios de d\u00favidas. \u00c9 esta For\u00e7a Amorosa interior a \u00fanica que pode nos lembrar quem somos e a import\u00e2ncia de nossa Presen\u00e7a e prop\u00f3sito aqui.<\/p>\n<p>E tudo depende de como estamos dispostos a ouvir essa voz interior de amor ou de continuar a encobri-la de medo.<\/p>\n<p>No Amor Infinito,<\/p>\n<p>Natalia Alba<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><strong>Autor: Natalia Alba \u00a0<\/strong><br \/>\n<strong>Fonte:\u00a0<a href=\"http:\/\/www.starseedsoul.com\/\">http:\/\/www.starseedsoul.com\/<\/a><\/strong><br \/>\n<strong>Tradu\u00e7\u00e3o:\u00a0<a href=\"https:\/\/www.sementesdasestrelas.com.br\/\">Sementes Das Estrelas<\/a>\u00a0\/ Giuliana Augusto<\/strong><\/p>\n<\/div>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 462<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>Amados, No momento, restaurar a f\u00e9 e a confian\u00e7a \u00e9 vital; se desejarmos continuar no caminho que escolhemos conscientemente e isto pode ser um desafio \u00e0s vezes, conforme progredimos e nos afastamos da matriz. Numa \u00e9poca em que tudo o que vemos pode parecer ca\u00f3tico, trabalhar na restaura\u00e7\u00e3o da f\u00e9 e da confian\u00e7a em nosso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-17118","post","type-post","status-publish","format-standard","hentry","category-espiritualidade"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=17118"}],"version-history":[{"count":0,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17118\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=17118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=17118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=17118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}