{"id":17250,"date":"2021-05-12T03:03:31","date_gmt":"2021-05-12T03:03:31","guid":{"rendered":"https:\/\/espacodosol.com\/blog.br\/?p=17250"},"modified":"2021-05-12T03:03:31","modified_gmt":"2021-05-12T03:03:31","slug":"o-reino-de-sirius","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2021\/05\/12\/o-reino-de-sirius\/","title":{"rendered":"O Reino de S\u00edrius"},"content":{"rendered":"<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17251\" src=\"https:\/\/espacodosol.com\/blog.br\/wp-content\/uploads\/2021\/05\/reino_sirius-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" \/><\/div>\n<div dir=\"auto\">S\u00edrius foi uma das primeiras \u00e1reas a ser colonizada por seres do grupo Lyra ap\u00f3s a Primeira Guerra Gal\u00e1ctica e \u00e9 extremamente avan\u00e7ada em um sentido metaf\u00edsico.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Djwhal Khul diz que &#8220;Sirius \u00e9 um dos centros ou universidades de treinamento mais avan\u00e7ados para os quais os Mestres Ascensos podem viajar.&#8221;<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">O caminho para S\u00edrius \u00e9 um dos Sete Caminhos para a Evolu\u00e7\u00e3o Superior que cada Alma deve escolher ao alcan\u00e7ar a Sexta Inicia\u00e7\u00e3o e \/ ou sua Ascens\u00e3o.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">A maioria dos Mestres Ascensos passaram por S\u00edrius para se iniciarem nos patames evolutivos Cr\u00edsticos \/ Nazarenos, inclusive o Grande Mestre Jesus, Sanat Kumara, Saint Germain e El-Morya.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">A estrela S\u00edrius \u00e9 conhecida como Estrela do C\u00e3o e \u00e9 membro da constela\u00e7\u00e3o de Canis Major. Fica a aproximadamente 8,7 anos-luz da Terra.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">\u00c9 uma das estrelas mais brilhantes que se pode observar no c\u00e9u noturno.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Ao pensar em S\u00edrius, devemos pensar nela em termos de ser uma consci\u00eancia grupal f\u00edsica e n\u00e3o f\u00edsica.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Os Sirianos tridimensionais visitaram as civiliza\u00e7\u00f5es Eg\u00edpcia e Maia no passado.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Os Sirianos deram aos Eg\u00edpcios muita informa\u00e7\u00e3o astron\u00f4mica e m\u00e9dica avan\u00e7ada.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Os Maias e os Incas tamb\u00e9m tinham um relacionamento muito pessoal com os Sirianos.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Muita informa\u00e7\u00e3o foi compartilhada, e \u00e9 interessante que a ra\u00e7a Maia pareceu desaparecer da face da Terra em um determinado ponto de sua hist\u00f3ria.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Os Sirianos deixaram para tr\u00e1s c\u00e1psulas do tempo para as futuras gera\u00e7\u00f5es descobrirem, uma das quais era supostamente a Caveira de Cristal.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Tamb\u00e9m existe uma liga\u00e7\u00e3o dos Altos Sacerdotes Sirianos com o Budismo, principalmente o que \u00e9 praticado no Himalaia.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Sabe-se que a Pedra Cintamani \u00e9 muito importante para o Budismo, e a Pedra Cintamani veio na verdade de meteoritos de um planeta que explodiu em S\u00edrius ap\u00f3s um Flash do Sol Central Gal\u00e1ctico h\u00e1 milh\u00f5es de anos, ent\u00e3o essas Pedras est\u00e3o imbu\u00eddas de Luz do Sol Central at\u00e9 hoje, e podem romper a malha an\u00f4mala da Matrix em torno delas, e s\u00e3o tamb\u00e9m Portais para S\u00edrius.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">No momento, os Sirianos est\u00e3o trabalhando conosco principalmente sem interven\u00e7\u00e3o direta. Eles foram fundamentais para nos ajudar na \u00e9poca da Atl\u00e2ntida durante o per\u00edodo catacl\u00edsmico.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Al\u00e9m disso, a Renascen\u00e7a, e muitos movimentos vanguardistas da Alta Cultura, Magia, e Filosofia, desde Atl\u00e2ntida, estavam sumamente ligados aos interesses do Reino de S\u00edrius.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Vemos que os Sirianos s\u00e3o muito ligados \u00e0 Arte e \u00e0 Beleza no geral, e s\u00e3o muito musicais tamb\u00e9m. Eles, naquele tempo da Atl\u00e2ntida, se misturaram conosco geneticamente, e esta \u00e9 a raz\u00e3o de termos o nosso lado criativo t\u00e3o preponderante.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Os Pleiadianos tamb\u00e9m se incluem nesta parte, como s\u00e3o as ra\u00e7as irm\u00e3s que tutelam o nosso povo para o melhor caminho evolutivo poss\u00edvel.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Seu ponto de vista atualmente na Terra \u00e9 que eles n\u00e3o considerar\u00e3o uma parceria mais ativa novamente, at\u00e9 que superemos a tend\u00eancia como povo de ser exploradora, cr\u00edtica e manipuladora.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Os guias tamb\u00e9m se referem \u00e0 S\u00edrius como um Sistema Estelar em que os residentes raramente s\u00e3o residentes permanentes.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">\u00c9 um local de encontro para aqueles que dominam seus pr\u00f3prios sistemas planet\u00e1rios e est\u00e3o se preparando para mais tarefas e miss\u00f5es. Eles falam sobre S\u00edrius como uma esta\u00e7\u00e3o importante para os Terranos que desejam continuar seu desenvolvimento espiritual.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Os seres de S\u00edrius que est\u00e3o visitando a Terra s\u00e3o muito bons na aplica\u00e7\u00e3o pr\u00e1tica de ideias te\u00f3ricas muito avan\u00e7adas, que est\u00e3o sendo trazidas de outras civiliza\u00e7\u00f5es extraterrestres muito avan\u00e7adas.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Eles est\u00e3o aqui para fundamentar e tornar utiliz\u00e1veis essas ideias e tecnologias avan\u00e7adas.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Os Sirianos ajudaram a construir as grandes pir\u00e2mides e templos do Egito. Eles tamb\u00e9m ajudaram na constru\u00e7\u00e3o de muitos dos t\u00faneis e vias para a Terra Interior.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">A marca registrada de muitos planetas em S\u00edrius \u00e9 que s\u00e3o principalmente aqu\u00e1ticos, contendo ra\u00e7as ex\u00f3ticas de mistura de homem e peixe, enquanto \u00e9 tamb\u00e9m o lar dos Cet\u00e1ceos, Golfinhos e Baleias, al\u00e9m de Canidaes e Felidaes, os Caninos e os Felinos. Muitas plantas medicinais tamb\u00e9m vieram de S\u00edrius, posso com seguran\u00e7a citar a Cannabis.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Eles estar\u00e3o muito envolvidos no futuro no estabelecimento da Idade de Ouro neste planeta. Voc\u00eas v\u00e3o ouvir falar deles cada vez mais.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\" style=\"text-align: justify;\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><strong>Autor: Assulus Sentinela<\/strong><\/div>\n<\/div>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 539<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>S\u00edrius foi uma das primeiras \u00e1reas a ser colonizada por seres do grupo Lyra ap\u00f3s a Primeira Guerra Gal\u00e1ctica e \u00e9 extremamente avan\u00e7ada em um sentido metaf\u00edsico. Djwhal Khul diz que &#8220;Sirius \u00e9 um dos centros ou universidades de treinamento mais avan\u00e7ados para os quais os Mestres Ascensos podem viajar.&#8221; O caminho para S\u00edrius \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-17250","post","type-post","status-publish","format-standard","hentry","category-espiritualidade"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=17250"}],"version-history":[{"count":0,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17250\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=17250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=17250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=17250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}