{"id":17811,"date":"2022-06-15T00:55:45","date_gmt":"2022-06-15T00:55:45","guid":{"rendered":"https:\/\/espacodosol.com\/blog.br\/?p=17811"},"modified":"2022-06-20T23:33:09","modified_gmt":"2022-06-21T02:33:09","slug":"energias-chegando-para-os-despertos","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2022\/06\/15\/energias-chegando-para-os-despertos\/","title":{"rendered":"Energias chegando para os despertos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17859\" src=\"http:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2022\/06\/fotons1-300x171.png\" alt=\"\" width=\"300\" height=\"171\" srcset=\"https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2022\/06\/fotons1-300x171.png 300w, https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2022\/06\/fotons1.png 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\">\u201cSauda\u00e7\u00f5es. N\u00f3s somos o Conselho Arcturiano. Temos o prazer de nos conectar com todos voc\u00eas.<\/p>\n<p style=\"text-align: justify;\">Estamos sempre \u00e0 procura de humanos que possam se alinhar conosco e nossas energias, nossas mensagens, porque sabemos o qu\u00e3o importante \u00e9 ter o que estamos enviando a voc\u00eas ancorado no reino f\u00edsico, e quanto mais voc\u00eas se abrem voc\u00eas at\u00e9 n\u00f3s e o que temos a oferecer, mais poderoso ser\u00e1 o impacto da perspectiva e energias Arcturianas.<\/p>\n<p style=\"text-align: justify;\">Procuramos estar a servi\u00e7o de toda a humanidade, n\u00e3o apenas aqueles de voc\u00eas que gostam de n\u00f3s e nos ouvem, ou leem nossas mensagens.<\/p>\n<p style=\"text-align: justify;\">Queremos ajudar toda a gal\u00e1xia e todo o Universo, independentemente de os seres que estamos ajudando nos conhecerem ou gostarem de n\u00f3s.<\/p>\n<p style=\"text-align: justify;\">E assim, quando olhamos para v\u00e1rios humanos na Terra que acreditamos estar prontos para mudar, mudar e se abrir para mais, calibramos as energias que estamos enviando para atrair esses indiv\u00edduos.<\/p>\n<p style=\"text-align: justify;\">Agora, n\u00e3o nos importamos se eles sabem que as energias vieram de n\u00f3s.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o estamos procurando pessoas para nos adorar ou nos seguir no sentido de uma religi\u00e3o, mas queremos que as pessoas recebam amor, porque \u00e9 disso que as pessoas realmente precisam.<\/p>\n<p style=\"text-align: justify;\">Queremos que as pessoas recebam apoio, porque \u00e9 disso que todos voc\u00eas realmente precisam.<\/p>\n<p style=\"text-align: justify;\">N\u00f3s queremos que voc\u00ea tenha seus chakras alinhados, para que voc\u00ea esteja ancorado, relaxado e aberto ao que \u00e9 que mais lhe serve.<\/p>\n<p style=\"text-align: justify;\">Queremos que as pessoas despertem para a verdade de quem elas realmente s\u00e3o como Seres da Fonte de Energia, e \u00e9 por isso que buscamos alcan\u00e7ar mais seres humanos.<\/p>\n<p style=\"text-align: justify;\">Continuaremos a faz\u00ea-lo, porque \u00e9 muito natural que um ser humano desperte, e podemos ajudar a facilitar esse processo, a empurrar as pessoas em uma determinada dire\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Mas o que est\u00e1 acontecendo na Terra \u00e9 inevit\u00e1vel. \u00c9 apenas hora de todos voc\u00eas passarem para experi\u00eancias novas e diferentes.<\/p>\n<p style=\"text-align: justify;\">Os que estiveram dispon\u00edveis para voc\u00eas l\u00e1 na Terra por tanto tempo est\u00e3o ficando desgastados, velhos e ineficazes.<\/p>\n<p style=\"text-align: justify;\">Para fazer com que as pessoas queiram voltar para casa na Fonte, elas precisam ser encorajadas a serem centradas no cora\u00e7\u00e3o, porque \u00e9 a\u00ed que voc\u00ea tem o maior acesso ao sentimento da Fonte dentro de voc\u00ea.<\/p>\n<p style=\"text-align: justify;\">\u00c9 por isso que incentivamos at\u00e9 mesmo aqueles que j\u00e1 nos recebem a parar de tentar descobrir tudo.<\/p>\n<p style=\"text-align: justify;\">Voc\u00ea n\u00e3o precisa saber tudo o que est\u00e1 acontecendo no mundo para estar acordado.<\/p>\n<p style=\"text-align: justify;\">Voc\u00ea tem suas pr\u00f3prias vidas, e as pessoas em suas vidas, que voc\u00ea precisa amar, perdoar e ter compaix\u00e3o, e as energias que estamos emitindo agora s\u00e3o para ajudar aqueles que recebem essa transmiss\u00e3o a serem mais centrados no cora\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">E as energias tamb\u00e9m ajudar\u00e3o aqueles que ainda n\u00e3o despertaram a sentir as energias que est\u00e3o dispon\u00edveis para eles dentro de seu pr\u00f3prio ser.<\/p>\n<p style=\"text-align: justify;\">Voc\u00eas s\u00e3o seres infinitos e eternos, e isso significa que voc\u00eas t\u00eam o infinito e a eternidade dentro de voc\u00eas.<\/p>\n<p style=\"text-align: justify;\">H\u00e1 muito mais a ser descoberto dentro de cada ser humano, e vamos encorajar as pessoas continuamente a fazer a jornada interior, porque a jornada que est\u00e1 acontecendo no reino f\u00edsico sempre ser\u00e1 cuidada, mas voc\u00ea pode faz\u00ea-lo de um lugar centrado no cora\u00e7\u00e3o, ou enquanto trope\u00e7ando no escuro \u00e0 procura de vil\u00f5es e conspira\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Aqueles de voc\u00eas que nos recebem regularmente sabem que n\u00e3o somos nada disso, e voc\u00eas tamb\u00e9m sabem que quando nos recebem, voc\u00eas sentem as atualiza\u00e7\u00f5es dentro de voc\u00eas, e sentem a forma como sua energia muda, e \u00e9 isso que estamos oferecendo a todos os humanos neste momento de v\u00e1rias maneiras, porque podemos sentir a import\u00e2ncia disso, especialmente neste momento no planeta Terra.<\/p>\n<p style=\"text-align: justify;\">N\u00f3s somos o Conselho Arcturiano e gostamos de nos conectar com voc\u00ea.\u201d<\/p>\n<p style=\"text-align: justify;\"><strong>Daniel Scranton<\/strong> \u2014 Fonte: <a href=\"https:\/\/danielscranton.com\/\">https:\/\/danielscranton.com\/<\/a><br \/>\nAnnalisa Ernica \u2013 <a href=\"http:\/\/www.atmalaboratory.com\">www.atmalaboratory.com<\/a>:<\/p>\n<p style=\"text-align: justify;\">Tradu\u00e7\u00e3o \u2014 Marco Iorio J\u00fanior \u2014 Tradutora e Editor exclusivos do Trabalhadores da Luz<\/p>\n<p>Postagem: Trabalhadores da Luz<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 602<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>\u201cSauda\u00e7\u00f5es. N\u00f3s somos o Conselho Arcturiano. Temos o prazer de nos conectar com todos voc\u00eas. Estamos sempre \u00e0 procura de humanos que possam se alinhar conosco e nossas energias, nossas mensagens, porque sabemos o qu\u00e3o importante \u00e9 ter o que estamos enviando a voc\u00eas ancorado no reino f\u00edsico, e quanto mais voc\u00eas se abrem voc\u00eas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-17811","post","type-post","status-publish","format-standard","hentry","category-espiritualidade"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=17811"}],"version-history":[{"count":3,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17811\/revisions"}],"predecessor-version":[{"id":17860,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17811\/revisions\/17860"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=17811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=17811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=17811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}