{"id":18124,"date":"2023-02-06T23:12:40","date_gmt":"2023-02-07T02:12:40","guid":{"rendered":"https:\/\/espacodosol.com\/blog\/?p=18124"},"modified":"2023-02-06T23:12:40","modified_gmt":"2023-02-07T02:12:40","slug":"dominando-a-vida-na-terra-mestre-kuthumi-e-o-senhor-melquisedeque","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2023\/02\/06\/dominando-a-vida-na-terra-mestre-kuthumi-e-o-senhor-melquisedeque\/","title":{"rendered":"Dominando a Vida na Terra &#8211; Mestre Kuthumi e o Senhor Melquisedeque"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-18125\" src=\"http:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/02\/earth-angel-marija-schwarz-1-241x300.jpg\" alt=\"\" width=\"241\" height=\"300\" srcset=\"https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/02\/earth-angel-marija-schwarz-1-241x300.jpg 241w, https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/02\/earth-angel-marija-schwarz-1.jpg 684w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>A vida na Terra \u00e9 curta, mas para os humanos uma vida inteira parece muito tempo, especialmente se algu\u00e9m sobrevive at\u00e9 os oitenta ou noventa anos.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Quando voc\u00ea \u00e9 crian\u00e7a, uma vida inteira parece uma eternidade, mas antes que voc\u00ea perceba, voc\u00ea se tornou um adulto e a inf\u00e2ncia \u00e9 apenas uma mem\u00f3ria.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Em um piscar de olhos, a velhice est\u00e1 chegando e muitas li\u00e7\u00f5es foram aprendidas ou desperdi\u00e7adas no meio.<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Ser humano, queridos, nada mais \u00e9 do que uma longa li\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Uma vida inteira de aprendizado que \u00e9 bem planejada antes da vida e observada durante a vida permitir\u00e1 que a alma cres\u00e7a em dire\u00e7\u00e3o \u00e0 maestria em um ritmo r\u00e1pido.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Se algu\u00e9m se perder no plano terrestre e se recusar a levar o aprendizado a bordo, a vida pode se tornar mais dif\u00edcil de viver, resultando na necessidade de reencarna\u00e7\u00e3o ap\u00f3s a morte.<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>A Vontade Divina \u00e9 que voc\u00ea domine seu livre arb\u00edtrio!\u00a0Superar o ego humano n\u00e3o \u00e9 tarefa f\u00e1cil, e quando os indiv\u00edduos podem colocar suas pr\u00f3prias necessidades de lado para ajudar os outros a aprender e evoluir, \u00e9 um sinal claro de que essa pessoa est\u00e1 no caminho certo para a maestria.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Ou\u00e7a a can\u00e7\u00e3o da sua alma.\u00a0O que est\u00e1 dizendo a voc\u00ea?\u00a0Qual \u00e9 o seu prop\u00f3sito aqui na Terra?\u00a0Al\u00e9m das raz\u00f5es normais para estar aqui, como estudar, trabalhar e ter uma fam\u00edlia, qual \u00e9 o prop\u00f3sito da sua vida que o leva a fazer a diferen\u00e7a no mundo?\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Se voc\u00ea est\u00e1 aqui, voc\u00ea deveria estar aqui!\u00a0Aproveite ao m\u00e1ximo o seu tempo e veja a li\u00e7\u00e3o em cada momento \u2013 voc\u00ea ser\u00e1 muito mais capaz de ver as b\u00ean\u00e7\u00e3os e, com isso, seu tempo na Terra ser\u00e1 milagroso!<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>H\u00e1 quatro coisas simples que voc\u00ea pode fazer para elevar suas vibra\u00e7\u00f5es acima do drama ao seu redor e ajudar sua experi\u00eancia de vida a ser menos desafiadora:<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><strong><span>Mantenha-se fundamentado. <\/span><\/strong> <span>Mantenha suas energias completamente ancoradas na M\u00e3e Terra, sempre ancorando conscientemente sua energia pela manh\u00e3, quando voc\u00ea se levantar. Sinta sua energia conectando-se \u00e0 M\u00e3e Terra e, em seguida, conecte-se \u00e0 luz do Criador. <\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Voc\u00ea vai se sentir muito mais em seu corpo durante todo o dia. Alternativamente, caminhe descal\u00e7o na grama molhada, na areia ou mesmo no tapete. Ou mergulhe na \u00e1gua e tenha consci\u00eancia de si mesmo no espa\u00e7o.<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><strong><span>Cuide da sua sa\u00fade. <\/span><\/strong> <span>Trate seu corpo como um templo, porque ele abriga seu esp\u00edrito e sua alma. Mantenha-se hidratado, alimente-se de forma saud\u00e1vel e exercite seu corpo. Certifique-se tamb\u00e9m de obter granizo suficiente e controlar a quantidade de estresse em sua vida.<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><strong><span>Aprenda a se amar novamente. <\/span><\/strong> <span>N\u00e3o \u00e9 poss\u00edvel ver tudo e todos com amor se voc\u00ea n\u00e3o consegue se ver assim! <\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>O universo gira em torno do amor e somente do amor. Encontre o amor por si mesmo e voc\u00ea ser\u00e1 capaz de ver as coisas de uma perspectiva muito mais elevada. <\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Voc\u00ea deve trabalhar para liberar as m\u00e1goas do passado e perdoar a si mesmo pelos erros do passado. N\u00e3o se olhe no espelho e veja sua apar\u00eancia f\u00edsica. Olhe, antes, para o seu cora\u00e7\u00e3o e veja a crian\u00e7a que h\u00e1 dentro. <\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>A maior parte do amor por si mesmo se dissipa no in\u00edcio ou no final da inf\u00e2ncia. Recupere seu amor por si mesmo enviando amor e perd\u00e3o a si mesmo quando crian\u00e7a. Alimente a crian\u00e7a interior e recupere o amor e o respeito por si mesmo que o Criador nunca perdeu.<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><strong><span>Mantenha-se conectado ao Amor Universal:<\/span><\/strong><span>\u00a0Embora seja importante estar ancorado e presente em seu corpo f\u00edsico, \u00e9 igualmente importante manter sua conex\u00e3o com seu eu superior, guias, anjos e o amor infinito do Universo.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Estar ciente do poder que seus pensamentos t\u00eam sobre sua realidade \u00e9 uma ferramenta que pode mudar sua vida de maneiras que voc\u00ea nunca imaginou.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Agrade\u00e7a ao Universo todos os dias pelo que voc\u00ea tem e pratique positividade em pensamentos, palavras e a\u00e7\u00f5es.\u00a0Veja cada dia como um presente e aprenda a perceber os sinais que seus guias est\u00e3o lhe dando para ajud\u00e1-lo em seu caminho.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Voc\u00ea nunca est\u00e1 sozinho e nada acontece por acaso.\u00a0Quanto mais voc\u00ea estiver conectado ao Esp\u00edrito, mais f\u00e1cil ser\u00e1 navegar pelos desafios do seu dia a dia.<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>Aproveitem ao m\u00e1ximo seu tempo na Terra, amados, e saibam que a maior parte do que est\u00e3o vivenciando foi escolhido por voc\u00eas para aprender e evoluir.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>As li\u00e7\u00f5es mais dif\u00edceis resultam em maior crescimento, e as li\u00e7\u00f5es que voc\u00ea aprende oferecem uma chance de se tornar um professor para os outros.\u00a0Isso pode ocorrer enquanto voc\u00ea ainda est\u00e1 vivo, ou pode optar por se tornar um guia espiritual muito mais tarde, ap\u00f3s o t\u00e9rmino de sua vida.\u00a0<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>O que quer que voc\u00ea escolha, lembre-se de que voc\u00ea sempre tem uma escolha.\u00a0Assuma o controle de sua vida e trabalhe com as ferramentas que o Universo lhe fornece para criar a vida que deseja.<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><span>N\u00f3s SOMOS o Mestre Kuthumi e o Senhor Melquisedeque.<\/span><\/p>\n<p class=\"has-medium-font-size\" style=\"text-align: justify;\"><a href=\"https:\/\/victoriacochrane44.com\/about\/\" target=\"_blank\" rel=\"noopener\"><span>Victoria Cochrane<\/span><\/a><\/p>\n<p><span style=\"\">Postagem: <\/span><span style=\"\">http:\/\/anjodeluz.ning.com\/<\/span><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 629<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>A vida na Terra \u00e9 curta, mas para os humanos uma vida inteira parece muito tempo, especialmente se algu\u00e9m sobrevive at\u00e9 os oitenta ou noventa anos.\u00a0 Quando voc\u00ea \u00e9 crian\u00e7a, uma vida inteira parece uma eternidade, mas antes que voc\u00ea perceba, voc\u00ea se tornou um adulto e a inf\u00e2ncia \u00e9 apenas uma mem\u00f3ria.\u00a0 Em um [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-18124","post","type-post","status-publish","format-standard","hentry","category-espiritualidade"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18124"}],"version-history":[{"count":1,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18124\/revisions"}],"predecessor-version":[{"id":18126,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18124\/revisions\/18126"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}