{"id":18145,"date":"2023-03-02T22:34:51","date_gmt":"2023-03-03T01:34:51","guid":{"rendered":"https:\/\/espacodosol.com\/blog\/?p=18145"},"modified":"2023-03-02T22:34:51","modified_gmt":"2023-03-03T01:34:51","slug":"comando-ashtar","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2023\/03\/02\/comando-ashtar\/","title":{"rendered":"Comando Ashtar"},"content":{"rendered":"<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xdj266r x126k92a\">\n<p dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-18147\" src=\"http:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/03\/ashthar-236x300.png\" alt=\"\" width=\"236\" height=\"300\" srcset=\"https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/03\/ashthar-236x300.png 236w, https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/03\/ashthar.png 275w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/><\/p>\n<p dir=\"auto\" style=\"text-align: justify;\">&#8220;O Comando Ashtar me informou que haver\u00e1 um alinhamento de campo energ\u00e9tico no planeta nos pr\u00f3ximos 12 dias, e isso levantar\u00e1 energias guardadas no mais profundo da Terra f\u00edsica e et\u00e9rica.<\/p>\n<p dir=\"auto\" style=\"text-align: justify;\">Haver\u00e1 uma massa de energia (n\u00e3o material) que subir\u00e1 e emergir\u00e1 na superf\u00edcie planet\u00e1ria.<\/p>\n<p dir=\"auto\" style=\"text-align: justify;\">Eles pedem que todos os Conscientes estejam com suas mentes em elevado padr\u00e3o, com boas conex\u00f5es e a\u00e7\u00f5es, para auxiliar a Terra nesse processo.<\/p>\n<p dir=\"auto\" style=\"text-align: justify;\">Algumas zonas da Terra poder\u00e3o sofrer com tens\u00f5es s\u00edsmicas.<\/p>\n<p dir=\"auto\" style=\"text-align: justify;\">A inten\u00e7\u00e3o deles ao pedir boas vibra\u00e7\u00f5es aos Conscientes da Terra \u00e9 para que sejam cada vez mais minimizadas as agita\u00e7\u00f5es mais intensas.<\/p>\n<\/div>\n<div dir=\"auto\">Eles continuam pedindo a UNI\u00c3O e AMOR entre todos para que o trabalho de libera\u00e7\u00e3o dessas velhas for\u00e7as aconte\u00e7a na maior harmonia poss\u00edvel (considerando ainda os restos c\u00e1rmicos planet\u00e1rios em dissolu\u00e7\u00e3o).<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Eles est\u00e3o em uma \u201ccorreria\u201d calibrando o campo magn\u00e9tico da Terra enquanto v\u00e1rias coisas acontecem ao mesmo tempo e precisam de n\u00f3s, os representantes da Federa\u00e7\u00e3o na superf\u00edcie para, como antenas, sustentarmos o maior equil\u00edbrio.<\/div>\n<div dir=\"auto\">\u00c9 at\u00e9 onde Jesus me permite ver e transmitir.<\/div>\n<div dir=\"auto\">Pela verdade, nada mais que a verdade.&#8221;<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<p dir=\"auto\" style=\"text-align: justify;\">Rafael (Neva\/<a class=\"x1i10hfl xjbqb8w x6umtig x1b1mbwd xaqea5y xav7gou x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xt0b8zv x1qq9wsj xo1l8bm\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/Gabriel.raio.lunar?__cft__[0]=AZUp66Y9VD_XaN70GEWMWQgnWOv1EJMEtX72flHW8AzZAqg4uEB_tI6fs05B5wxCJzcTNG50Mqu1VE44UbJDQkYDjjOiOmqre4faml7XwV8Sr3JLUvgn30hXC65VWdU_pqs5aBe_R9KFFMJNYU6_6kMgzzTLJXVlOwUE0GLIXnkNF9WlnxPlYdX1p8xFXqcERv4&amp;__tn__=-]K-R\"><span class=\"xt0psk2\">Gabriel RL<\/span><\/a>) em transmiss\u00e3o do Comando Ashtar<\/p>\n<\/div>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 522<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>&#8220;O Comando Ashtar me informou que haver\u00e1 um alinhamento de campo energ\u00e9tico no planeta nos pr\u00f3ximos 12 dias, e isso levantar\u00e1 energias guardadas no mais profundo da Terra f\u00edsica e et\u00e9rica. Haver\u00e1 uma massa de energia (n\u00e3o material) que subir\u00e1 e emergir\u00e1 na superf\u00edcie planet\u00e1ria. Eles pedem que todos os Conscientes estejam com suas mentes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-18145","post","type-post","status-publish","format-standard","hentry","category-espiritualidade"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18145"}],"version-history":[{"count":1,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18145\/revisions"}],"predecessor-version":[{"id":18148,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18145\/revisions\/18148"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}