{"id":18150,"date":"2023-03-06T23:03:09","date_gmt":"2023-03-07T02:03:09","guid":{"rendered":"https:\/\/espacodosol.com\/blog\/?p=18150"},"modified":"2023-03-06T23:03:09","modified_gmt":"2023-03-07T02:03:09","slug":"criadora-o-universo-ve","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2023\/03\/06\/criadora-o-universo-ve\/","title":{"rendered":"Criador(a) \u2013 \u201cO universo v\u00ea\u2026\u201d"},"content":{"rendered":"<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<div class=\"separator\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-18151\" src=\"http:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/03\/criador-300x171.jpeg\" alt=\"\" width=\"381\" height=\"217\" srcset=\"https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/03\/criador-300x171.jpeg 300w, https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/03\/criador.jpeg 700w\" sizes=\"auto, (max-width: 381px) 100vw, 381px\" \/><\/p>\n<p>Quando voc\u00ea se olha no espelho, o que voc\u00ea v\u00ea? Voc\u00ea pode ver suas imperfei\u00e7\u00f5es; rugas, um pouco de peso extra ou, talvez, uma pessoa infeliz ou insatisfeita. O que o Universo v\u00ea?<\/p>\n<p>Ele v\u00ea uma vida inteira de experi\u00eancia!<\/p>\n<p>Ele v\u00ea algu\u00e9m que teve sua parcela de tristeza e sofrimento e ainda consegue abra\u00e7ar e celebrar as coisas boas.<\/p>\n<p>Ele v\u00ea um ser humano que superou o que outros podem chamar de desafios imposs\u00edveis e saiu mais forte do outro lado.<\/p>\n<p>V\u00ea algu\u00e9m que tem coragem de ficar na Terra independente dos traumas que passou.<\/p>\n<p>Ele v\u00ea uma pessoa que est\u00e1 se doando, amando e crescendo mesmo que, neste momento, voc\u00ea se sinta estagnado e parado.<\/p>\n<p>Ele v\u00ea uma alma incr\u00edvel envolta em um corpo que pode nem sempre se comportar ou ter a apar\u00eancia que voc\u00ea deseja, mas \u00e9 seu e \u00e9 maravilhoso.<\/p>\n<p>Independente do que voc\u00ea veja, o Universo sempre viu e sempre ver\u00e1 o que h\u00e1 de melhor em voc\u00ea.<\/p>\n<p>\u00c9 hora de voc\u00ea come\u00e7ar a fazer o mesmo!<\/p>\n<p>Criador(a)<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Canal: Jennifer Farley<br \/>\nFonte:\u00a0<a href=\"https:\/\/thecreatorwritings.wordpress.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/thecreatorwritings.wordpress.com<\/a><br \/>\nTradu\u00e7\u00e3o:\u00a0<a href=\"https:\/\/www.decoracaoacoracao.blog.br\/\" target=\"_blank\" rel=\"noopener\">Stela Lecocq \/ De Cora\u00e7\u00e3o a Cora\u00e7\u00e3o\u00a0<\/a><\/strong><\/p>\n<p>Fonte postagem: www.sementesdasestrelas.com.br<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 453<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>Quando voc\u00ea se olha no espelho, o que voc\u00ea v\u00ea? Voc\u00ea pode ver suas imperfei\u00e7\u00f5es; rugas, um pouco de peso extra ou, talvez, uma pessoa infeliz ou insatisfeita. O que o Universo v\u00ea? Ele v\u00ea uma vida inteira de experi\u00eancia! Ele v\u00ea algu\u00e9m que teve sua parcela de tristeza e sofrimento e ainda consegue abra\u00e7ar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-18150","post","type-post","status-publish","format-standard","hentry","category-espiritualidade"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18150"}],"version-history":[{"count":1,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18150\/revisions"}],"predecessor-version":[{"id":18152,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18150\/revisions\/18152"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}