{"id":18161,"date":"2023-03-31T00:46:10","date_gmt":"2023-03-31T03:46:10","guid":{"rendered":"https:\/\/espacodosol.com\/blog\/?p=18161"},"modified":"2023-03-31T00:46:10","modified_gmt":"2023-03-31T03:46:10","slug":"ashian-pre-choque-e-pos-choque","status":"publish","type":"post","link":"https:\/\/espacodosol.com\/blog\/index.php\/2023\/03\/31\/ashian-pre-choque-e-pos-choque\/","title":{"rendered":"Ashian \u2013 \u201cPr\u00e9-choque e p\u00f3s-choque\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-18170\" src=\"http:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/03\/Liberdade-300x171.png\" alt=\"\" width=\"375\" height=\"214\" srcset=\"https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/03\/Liberdade-300x171.png 300w, https:\/\/espacodosol.com\/blog\/wp-content\/uploads\/2023\/03\/Liberdade.png 700w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\r\n<p>Ashian: Amados portadores de luz e todos que ressoam com essas palavras, n\u00f3s os cumprimentamos ao entrarem no per\u00edodo mais tumultuado da hist\u00f3ria registrada da humanidade.<\/p>\r\n<p>Queremos falar das ondas de choque que j\u00e1 est\u00e3o reverberando em sua psique coletiva, pois a velha estrutura entrou em colapso e o novo ainda n\u00e3o foi revelado. N\u00e3o apenas as energias carregadas negativamente foram desalojadas e est\u00e3o procurando ativamente por novos \u2018lares\u2019 \u2013 elas buscam a energia negativa da dor, medo, ansiedade, estresse para se alimentar \u2013 mas a psique coletiva humana sabe que chegou a hora do jogo final. Eles podem n\u00e3o reconhecer, mas o choque da queda da cabala e das estruturas que dependem dela \u00e9 t\u00e3o profundo que todos o est\u00e3o sentindo, mesmo que n\u00e3o estejam cientes de que \u00e9 isso que est\u00e1 aumentando sua ansiedade.<\/p>\r\n<p>Jennifer: Sim, \u00e9 exatamente isso que eu queria discutir com voc\u00ea. Nos \u00faltimos dias, tenho estado extremamente ciente de sentimentos profundos de que algo est\u00e1 muito \u2018errado\u2019; h\u00e1 uma energia com a qual n\u00e3o estou familiarizada se movendo dentro de mim que me deixa excepcionalmente desconfort\u00e1vel \u2013 sinto tonturas, palpita\u00e7\u00f5es, n\u00e1useas \u2013 e tamb\u00e9m acesso imagens ou sentimentos de pessoas chorando de terror. N\u00e3o seria exagero dizer que minha cabe\u00e7a parece um filme de terror agora.<\/p>\r\n<p>A: Sim, estamos cientes: o que voc\u00ea est\u00e1 experimentando e descrevendo ressoar\u00e1 em muitos que trabalham com as energias e com os empatas que alcan\u00e7aram uma vibra\u00e7\u00e3o em que est\u00e3o trabalhando para o bem coletivo. A primeira coisa que dir\u00edamos \u00e9 para reconhecer os sentimentos. Reconhecer \u00e9 ver (n\u00e3o fechar os olhos, ou potencializar), isso fornece um canal para a ang\u00fastia e o que \u00e9 reconhecido \u00e9 dissipado.<\/p>\r\n<p>Embora muitos n\u00e3o estejam conscientes das mudan\u00e7as nos bastidores, suas almas est\u00e3o conscientes. O atraso no desenrolar do Evento do despertar \u00e9, em parte, para dar tempo \u00e0 psique coletiva para que tome consci\u00eancia do que aconteceu. Essa prepara\u00e7\u00e3o ocorre inconscientemente, com a certeza de que o mal foi derrotado e as velhas estruturas est\u00e3o desmoronando enquanto falamos. Embutidas nisso tamb\u00e9m est\u00e3o as chaves que cada ser conhece para encontrar seu caminho durante este momento e refazer suas vidas de uma maneira que ressoe com seu eu superior.<\/p>\r\n<p>J: Ent\u00e3o \u00e9 uma esp\u00e9cie de prepara\u00e7\u00e3o inconsciente?<\/p>\r\n<p>A: Sim, essa \u00e9 uma boa maneira de descrever.<\/p>\r\n<p>J: E como lidamos com isso? Como ajudamos os outros a lidarem com isso?<\/p>\r\n<p>A: A primeira coisa a lembrar \u00e9 que quanto mais sutil for o trabalho energ\u00e9tico, mais eficaz ele ser\u00e1. Com isso queremos dizer que: a energia funciona do sutil \u2013 ps\u00edquico, emocional, mental \u2013 at\u00e9 esta express\u00e3o f\u00edsica em seu corpo, atrav\u00e9s dos sintomas que voc\u00ea descreve.<\/p>\r\n<p>Enviar a chama violeta aos sentimentos e imagens que surgem \u00e9 uma forma de diminuir o grau de severidade com que eles se manifestam. Pedir a um ser divino, mestre ascensionado ou anjos para transmutarem as energias inferiores \u00e9 outra maneira. A ora\u00e7\u00e3o ajuda enormemente quando vem do cora\u00e7\u00e3o. Estas s\u00e3o apenas algumas maneiras de trabalhar com as energias sutis.<\/p>\r\n<p>Voc\u00ea tamb\u00e9m precisa cuidar do seu corpo, pois esses pensamentos e sentimentos ressoam em sua forma f\u00edsica. Essas a\u00e7\u00f5es \u2013 e todos voc\u00eas s\u00e3o lembrados de criar seu pr\u00f3prio \u2018card\u00e1pio\u2019 de solu\u00e7\u00f5es de autocuidado, de ioga e medita\u00e7\u00e3o a banhos, dan\u00e7a e pintura \u2013 ir\u00e3o fundamentar os sentimentos de equil\u00edbrio em seus corpos e para o coletivo.<\/p>\r\n<p>Nosso ponto final \u00e9 este: n\u00e3o h\u00e1 necessidade de ser perfeito, para passar por este tempo em completo equil\u00edbrio. Fazer isso seria uma distor\u00e7\u00e3o. Todos ter\u00e3o que enfrentar e lidar com algum aspecto de choque e dor, conforme decidido com seu eu superior antes da encarna\u00e7\u00e3o. Portanto, passe por seus processos da melhor maneira poss\u00edvel. N\u00e3o temos expectativas sobre voc\u00ea, nem sobre o seu eu superior. N\u00e3o h\u00e1 classifica\u00e7\u00e3o, nem \u2018certo\u2019 ou \u2018errado\u2019. Existe simplesmente voc\u00ea sendo e fazendo o melhor que pode em qualquer momento, armado com o conhecimento de que voc\u00ea passar\u00e1 por esses \u2018fogos do inferno\u2019, e tanto voc\u00ea quanto a humanidade ser\u00e3o transformados para sempre, como a f\u00eanix renascendo das cinzas.<\/p>\r\n<p>J: Obrigada, Asian.<\/p>\r\n<p>A: Estamos com voc\u00eas, todos voc\u00eas. Chame-nos e estaremos l\u00e1 para confort\u00e1-los.<\/p>\r\n<p>NOTAS: Algo que surgiu logo ap\u00f3s esta sess\u00e3o foi que este \u00e9 o \u2018Momento da Arca\u2019: a arca da humanidade foi preparada, as \u00e1guas agora est\u00e3o subindo. Vamos resistir a esta tempestade. Assim como a pomba trouxe o ramo de oliveira para sinalizar o fim do dil\u00favio, seremos transformados em nosso eu f\u00eanix, com o cumprimento do processo de liberdade f\u00edsica e espiritual incorporado na met\u00e1fora da pomba e do ramo de oliveira.<\/p>\r\n<p><strong>Canal\/Autor: Jennifer Crokaert<\/strong><br \/><strong>Fonte prim\u00e1ria:\u00a0<a href=\"https:\/\/jennifercrokaert.com\/ashian-pre-shock-and-post-shock\/\">https:\/\/jennifercrokaert.com\/ashian-pre-shock-and-post-shock\/<\/a><\/strong><br \/><strong>Tradu\u00e7\u00e3o e Postagem:<a href=\"https:\/\/www.sementesdasestrelas.com.br\/\">\u00a0Sementes das Estrelas<\/a>\u00a0\/ Iara L. Ferraz<\/strong><\/p>\r\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 490<\/span><span class='epvc-label'> Views<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>Ashian: Amados portadores de luz e todos que ressoam com essas palavras, n\u00f3s os cumprimentamos ao entrarem no per\u00edodo mais tumultuado da hist\u00f3ria registrada da humanidade. Queremos falar das ondas de choque que j\u00e1 est\u00e3o reverberando em sua psique coletiva, pois a velha estrutura entrou em colapso e o novo ainda n\u00e3o foi revelado. N\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-18161","post","type-post","status-publish","format-standard","hentry","category-espiritualidade"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18161"}],"version-history":[{"count":2,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18161\/revisions"}],"predecessor-version":[{"id":18171,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18161\/revisions\/18171"}],"wp:attachment":[{"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacodosol.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}